{"id":7461,"date":"2012-08-24T08:00:00","date_gmt":"2012-08-24T11:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_principe_esta_nu\/"},"modified":"2012-08-24T08:00:00","modified_gmt":"2012-08-24T11:00:00","slug":"o_principe_esta_nu","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_principe_esta_nu\/","title":{"rendered":"O pr\u00edncipe est\u00e1 nu"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">         <\/p>\n<p> <\/b> O pr\u00edncipe Harry passava f\u00e9rias em Las Vegas. Encontrou amigos. Promoveu  festas. Participou de noitadas. E\u2026 se descuidou. Deixou-se flagrar do jeitinho  que veio ao mundo. As fotos do pelad\u00e3o ganharam Europa, Fran\u00e7a e Bahia.  Internet, jornais e revistas as exibiram. Ele n\u00e3o pensou duas vezes. Fez as  malas e voltou pra Londres.    <\/p>\n<p>Mas o notici\u00e1rio deixou uma d\u00favida nos brasileiros. Alguns escreveram  <i>nu<\/i> com acento. Outros, sem acento. E da\u00ed? Monoss\u00edlabos t\u00f4nicos terminados  em <b>u<\/b> jogam no time dos terminados em <b>i<\/b>. N\u00e3o aceitam grampinho nem  a pedido de Sua Majestade: <i>nu, cru, li, vi<\/i>. <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   &nbsp;<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pr\u00edncipe Harry passava f\u00e9rias em Las Vegas. Encontrou amigos. Promoveu festas. Participou de noitadas. E\u2026 se descuidou. Deixou-se flagrar do jeitinho que veio ao mundo. As fotos do pelad\u00e3o ganharam Europa, Fran\u00e7a e Bahia. Internet, jornais e revistas as exibiram. Ele n\u00e3o pensou duas vezes. Fez as malas e voltou pra Londres. Mas o notici\u00e1rio deixou uma d\u00favida nos brasileiros. Alguns escreveram nu com [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7461","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7461"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7461\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}