{"id":7340,"date":"2012-04-21T00:00:00","date_gmt":"2012-04-21T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/mania_nacional\/"},"modified":"2012-04-21T00:00:00","modified_gmt":"2012-04-21T03:00:00","slug":"mania_nacional","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/mania_nacional\/","title":{"rendered":"Mania nacional"},"content":{"rendered":"<div><strong> <\/p>\n<p> <\/strong><\/div>\n<div>&nbsp;<\/div>\n<div style=\"font-family: verdana,sans-serif\">M\u00e9dicos p\u00f5em a boca no mundo. De um lado, falam&nbsp;das m\u00e1s condi\u00e7\u00f5es de trabalho. De  outro,&nbsp;da escassez de profissionais.  Por fim,&nbsp;de h\u00e1bito bem brasileiro.  Nove em cada&nbsp;10 tupiniquins tomam  rem\u00e9dio por conta pr\u00f3pria. Automedicam-se. Vale a pena, por isso, debru\u00e7ar-se  sobre o prefixo auto-. Como escrever os derivados? Com h\u00edfen? Sem h\u00edfen? A  diss\u00edlaba pede tracinho quando seguida de h ou o. No mais, \u00e9  tudo colado. Quando seguido de r ou s, dobra as consoantes  para manter a pron\u00fancia: auto-hipnose, auto-observa\u00e7\u00e3o, autoafirma\u00e7\u00e3o,  autodidata, autobiografia, autorretrato, autossufici\u00eancia.<\/div>\n<div style=\"font-family: verdana,sans-serif\">&nbsp;<\/div>\n<div style=\"font-family: verdana,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; M\u00e9dicos p\u00f5em a boca no mundo. De um lado, falam&nbsp;das m\u00e1s condi\u00e7\u00f5es de trabalho. De outro,&nbsp;da escassez de profissionais. Por fim,&nbsp;de h\u00e1bito bem brasileiro. Nove em cada&nbsp;10 tupiniquins tomam rem\u00e9dio por conta pr\u00f3pria. Automedicam-se. Vale a pena, por isso, debru\u00e7ar-se sobre o prefixo auto-. Como escrever os derivados? Com h\u00edfen? Sem h\u00edfen? A diss\u00edlaba pede tracinho quando seguida de h ou o. No mais, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7340","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7340"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7340\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}