{"id":7243,"date":"2012-04-11T00:00:00","date_gmt":"2012-04-11T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta_2-20\/"},"modified":"2015-11-13T10:23:03","modified_gmt":"2015-11-13T12:23:03","slug":"leitor_pergunta_2-20","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta_2-20\/","title":{"rendered":"Leitor pergunta 2"},"content":{"rendered":"\n<p> Uma das duas pessoas n\u00e3o ir\u00e1. A maioria das pessoas n\u00e3o ir\u00e1.  <\/p>\n<p>A  concord\u00e2ncia est\u00e1 correta?  (Ant\u00f4nio Mauro) <\/p>\n<p><b><\/b> Nota  10, Antonio. A segunda frase tem alternativa. O verbo pode concordar  com  o n\u00facleo do sujeito (maioria) ou com o complemento (pessoas). No  caso, \u00e9 acertar  ou acertar: <i>A maioria das pessoas n\u00e3o ir\u00e1 (ir\u00e3o) \u00e0  festa.<\/i>   <\/p>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\" align=\"left\"><strong> <\/p>\n<p><\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma das duas pessoas n\u00e3o ir\u00e1. A maioria das pessoas n\u00e3o ir\u00e1. A concord\u00e2ncia est\u00e1 correta? (Ant\u00f4nio Mauro) Nota 10, Antonio. A segunda frase tem alternativa. O verbo pode concordar com o n\u00facleo do sujeito (maioria) ou com o complemento (pessoas). No caso, \u00e9 acertar ou acertar: A maioria das pessoas n\u00e3o ir\u00e1 (ir\u00e3o) \u00e0 festa.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-7243","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7243"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7243\/revisions"}],"predecessor-version":[{"id":11371,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7243\/revisions\/11371"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}