{"id":7053,"date":"2012-03-19T09:05:00","date_gmt":"2012-03-19T12:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/de_volta_ao_passado-4\/"},"modified":"2012-03-19T09:05:00","modified_gmt":"2012-03-19T12:05:00","slug":"de_volta_ao_passado-4","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/de_volta_ao_passado-4\/","title":{"rendered":"De volta ao passado"},"content":{"rendered":"<p>&nbsp;<b>        <\/b> Elizandro lembrou uma historinha dos tempos da escola prim\u00e1ria. O professor  criou calo na l\u00edngua de tanto repetir:  <\/p>\n<p>\u2014 Quem cede o empr\u00e9stimo <b>empresta<\/b>. Quem recebe o empr\u00e9stimo  <b>toma<\/b> <b>emprestado<\/b>.  <\/p>\n<p>Um aluno maroto aproveitou a confus\u00e3o dos colegas. Perguntou \u00e0 mestra:  <\/p>\n<p>\u2014 Tia, posso emprestar o l\u00e1pis?  <\/p>\n<p>Ela fez ouvidos moucos. Ele insistiu:  <\/p>\n<p>\u2014 Tia, posso emprestar o l\u00e1pis?  <\/p>\n<p>Irritada, a senhora voltou \u00e0 carga:  <\/p>\n<p>\u2014 J\u00e1 repeti mil vezes que n\u00e3o \u00e9 <i>emprestar o l\u00e1pis<\/i> que se diz, mas  <i>tomar o l\u00e1pis emprestado.<\/i>  <\/p>\n<p>O garoto teve orgasmos \u00edntimos. Mas n\u00e3o exibiu o prazer. Com cara s\u00e9ria,  respondeu como quem n\u00e3o quer nada:  <\/p>\n<p>\u2014 O l\u00e1pis \u00e9 meu, professora.  <\/p>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\" align=\"left\"><strong> <\/p>\n<p><\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Elizandro lembrou uma historinha dos tempos da escola prim\u00e1ria. O professor criou calo na l\u00edngua de tanto repetir: \u2014 Quem cede o empr\u00e9stimo empresta. Quem recebe o empr\u00e9stimo toma emprestado. Um aluno maroto aproveitou a confus\u00e3o dos colegas. Perguntou \u00e0 mestra: \u2014 Tia, posso emprestar o l\u00e1pis? Ela fez ouvidos moucos. Ele insistiu: \u2014 Tia, posso emprestar o l\u00e1pis? Irritada, a senhora voltou \u00e0 [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7053","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7053"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7053\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}