{"id":7051,"date":"2012-07-01T11:50:00","date_gmt":"2012-07-01T14:50:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/berco_da_palavra_4-11\/"},"modified":"2012-07-01T11:50:00","modified_gmt":"2012-07-01T14:50:00","slug":"berco_da_palavra_4-11","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/berco_da_palavra_4-11\/","title":{"rendered":"Ber\u00e7o da palavra 4"},"content":{"rendered":"<p>     <b> <\/p>\n<p><\/b>M\u00e1rcio Cotrim<b> <\/p>\n<p><\/b><b> <\/p>\n<p><\/b><b>Fisco<\/b>  <\/p>\n<p>A curiosidade reside no significado inicial do termo (no latim, <i>fiscus<\/i>): <i>cesto de vime ou junco onde se esmagavam as uvas das vindimas ou as azeitonas<\/i>.     Algu\u00e9m, um dia, utilizou o cesto para guardar as economias em moedas, ou algum cobrador de impostos o utilizou para recolher o dinheiro, o que \u00e9 mais prov\u00e1vel, pois o fisco se tornou a parte da renda do Estado destinada \u00e0 manuten\u00e7\u00e3o pessoal do monarca, veja voc\u00ea. Talvez essa finalidade tenha dado \u00e0 palavra o ber\u00e7o do desagrado com que hoje pagamos tributos.      <\/p>\n<p>O h\u00e1bito de lan\u00e7ar moedas ao cesto ainda hoje \u00e9 usado nas igrejas na coleta de donativos para a conserva\u00e7\u00e3o do templo e dos gastos do seu sacerdote.Por seu turno, a origem dos <i>fiscus<\/i> latino \u00e9, hipoteticamente, uma palavra do indo-europeu <i>bisku<\/i>, que ainda est\u00e1 no ingl\u00eas <i>basket<\/i>, o cesto do basquetebol. Nunca esquecer que imposto \u00e9 algo imposto ao cidad\u00e3o. Ali\u00e1s, segundo Mill\u00f4r Fernandes, se fosse facultativo eles iam ver uma coisa.     &nbsp;    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1rcio Cotrim Fisco A curiosidade reside no significado inicial do termo (no latim, fiscus): cesto de vime ou junco onde se esmagavam as uvas das vindimas ou as azeitonas. Algu\u00e9m, um dia, utilizou o cesto para guardar as economias em moedas, ou algum cobrador de impostos o utilizou para recolher o dinheiro, o que \u00e9 mais prov\u00e1vel, pois o fisco se tornou a parte da [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7051","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7051"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7051\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}