{"id":7031,"date":"2012-06-29T00:00:00","date_gmt":"2012-06-29T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-129\/"},"modified":"2015-11-13T10:21:35","modified_gmt":"2015-11-13T12:21:35","slug":"leitor_pergunta-129","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-129\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"\n<p>Li esta frase no jornal: &#8220;O grupo alerta a todos que&nbsp;atacam o presidente s\u00edrio que vamos cortar seus  pesco\u00e7os antes de chegarem a Damasco&#8221;. Reli o texto. N\u00e3o entendi o plural de  pesco\u00e7o. Conclu\u00ed, ent\u00e3o, que os rebeldes s\u00e3o descendentes da Hidra de Lerna, que  tinha nove cabe\u00e7as. Ser\u00e1? (Carlos Medeiros) <\/p>\n<p> <strong> <\/p>\n<p><\/strong>  <\/p>\n<p>As palavras s\u00e3o cheias de manhas. Algumas t\u00eam plural. Mas, em  certas constru\u00e7\u00f5es, s\u00f3 se usam no singular. \u00c9 o caso das partes do corpo.  Cabe\u00e7a, por exemplo. Dizemos que os presentes balan\u00e7aram a cabe\u00e7a (n\u00e3o  as cabe\u00e7as) porque cada um s\u00f3 tem uma cabe\u00e7a. O mesmo ocorre com pesco\u00e7o. A  frase mereceria nota 10 se estivesse escrita assim: O grupo alerta a todos  que&nbsp;atacam o presidente s\u00edrio que  vamos lhes cortar o pesco\u00e7o antes de chegarem a Damasco.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Li esta frase no jornal: &#8220;O grupo alerta a todos que&nbsp;atacam o presidente s\u00edrio que vamos cortar seus pesco\u00e7os antes de chegarem a Damasco&#8221;. Reli o texto. N\u00e3o entendi o plural de pesco\u00e7o. Conclu\u00ed, ent\u00e3o, que os rebeldes s\u00e3o descendentes da Hidra de Lerna, que tinha nove cabe\u00e7as. Ser\u00e1? (Carlos Medeiros) As palavras s\u00e3o cheias de manhas. Algumas t\u00eam plural. Mas, em certas constru\u00e7\u00f5es, s\u00f3 [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-7031","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7031"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7031\/revisions"}],"predecessor-version":[{"id":11353,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7031\/revisions\/11353"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}