{"id":7010,"date":"2012-06-28T08:00:00","date_gmt":"2012-06-28T11:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/voltaire_escreveu-3\/"},"modified":"2012-06-28T08:00:00","modified_gmt":"2012-06-28T11:00:00","slug":"voltaire_escreveu-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/voltaire_escreveu-3\/","title":{"rendered":"Voltaire escreveu"},"content":{"rendered":"\n<p>&#8220;Perdoe-me, senhora, se escrevi carta t\u00e3o comprida. N\u00e3o tive tempo de faz\u00ea-la  curta.&#8221; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Perdoe-me, senhora, se escrevi carta t\u00e3o comprida. N\u00e3o tive tempo de faz\u00ea-la curta.&#8221;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7010","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7010"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7010\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}