{"id":69,"date":"2015-01-23T18:00:00","date_gmt":"2015-01-23T18:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/01\/23\/erramos-11\/"},"modified":"2015-11-12T12:15:30","modified_gmt":"2015-11-12T14:15:30","slug":"erramos-11","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-11\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&#8220;Paulo Roberto Costa acredita que Nestor Cerver\u00f3 e Fernando  Baiano podem ter embolsado at\u00e9 US$ 30 milh\u00f5es&#8221;, escrevemos na p\u00e1g. 2.&nbsp;Ora veja! Muitos mataram e enterraram o  subjuntivo. N\u00f3s estamos entre eles. Mas o homem p\u00f5e e o texto disp\u00f5e. O per\u00edodo  exige que o ressuscitemos. Assim<i>: Paulo Roberto Costa acredita que Nestor  Cerver\u00f3 e Fernando Baiano possam ter embolsado at\u00e9 US$ 30  milh\u00f5es.<\/i><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Paulo Roberto Costa acredita que Nestor Cerver\u00f3 e Fernando Baiano podem ter embolsado at\u00e9 US$ 30 milh\u00f5es&#8221;, escrevemos na p\u00e1g. 2.&nbsp;Ora veja! Muitos mataram e enterraram o subjuntivo. N\u00f3s estamos entre eles. Mas o homem p\u00f5e e o texto disp\u00f5e. O per\u00edodo exige que o ressuscitemos. Assim: Paulo Roberto Costa acredita que Nestor Cerver\u00f3 e Fernando Baiano possam ter embolsado at\u00e9 US$ 30 milh\u00f5es. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-69","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/69\/revisions"}],"predecessor-version":[{"id":1376,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/69\/revisions\/1376"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=69"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=69"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}