{"id":6875,"date":"2012-06-17T06:00:00","date_gmt":"2012-06-17T09:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_berco_da_palavra_2-3\/"},"modified":"2012-06-17T06:00:00","modified_gmt":"2012-06-17T09:00:00","slug":"o_berco_da_palavra_2-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_berco_da_palavra_2-3\/","title":{"rendered":"O ber\u00e7o da palavra 2"},"content":{"rendered":"\n<p>        Europa  <\/p>\n<p>M\u00e1rcio Cotrim  <\/p>\n<p>Falemos da origem do nome <b>Europa<\/b>. A mitologia ensina que ela foi uma princesa fen\u00edcia muito bela, que despertou o amor em Zeus, deus-rei do Olimpo. Arrebatado pela paix\u00e3o, ele transformou-se em touro branco e a raptou, levando-a para a ilha de Creta. Desse encontro teria nascido o Minotauro, que viria a habitar o famoso labirinto onde devoraria os viajantes incautos.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Europa M\u00e1rcio Cotrim Falemos da origem do nome Europa. A mitologia ensina que ela foi uma princesa fen\u00edcia muito bela, que despertou o amor em Zeus, deus-rei do Olimpo. Arrebatado pela paix\u00e3o, ele transformou-se em touro branco e a raptou, levando-a para a ilha de Creta. Desse encontro teria nascido o Minotauro, que viria a habitar o famoso labirinto onde devoraria os viajantes incautos.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6875","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6875"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6875\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}