{"id":6804,"date":"2012-10-18T13:32:00","date_gmt":"2012-10-18T16:32:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-124\/"},"modified":"2015-11-13T10:21:13","modified_gmt":"2015-11-13T12:21:13","slug":"leitor_pergunta-124","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-124\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">      <\/p>\n<p>   <\/b> Na discuss\u00e3o de projetos de lei, fala-se em &#8220;pr\u00e9via previs\u00e3o or\u00e7ament\u00e1ria&#8221;.  N\u00e3o \u00e9 redundante? (Ednei Amaral) <\/p>\n<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">      <\/p>\n<p>   <\/b> Voc\u00ea tem raz\u00e3o. Prever \u00e9 ver antes. O pr\u00e9via sobra.  X\u00f4!&nbsp;Basta previs\u00e3o  or\u00e7ament\u00e1ria.  <\/p>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\" align=\"left\">\n<div align=\"left\"><strong> <\/p>\n<p><\/strong><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na discuss\u00e3o de projetos de lei, fala-se em &#8220;pr\u00e9via previs\u00e3o or\u00e7ament\u00e1ria&#8221;. N\u00e3o \u00e9 redundante? (Ednei Amaral) Voc\u00ea tem raz\u00e3o. Prever \u00e9 ver antes. O pr\u00e9via sobra. X\u00f4!&nbsp;Basta previs\u00e3o or\u00e7ament\u00e1ria.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-6804","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6804"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6804\/revisions"}],"predecessor-version":[{"id":11327,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6804\/revisions\/11327"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}