{"id":678,"date":"2015-10-04T00:03:00","date_gmt":"2015-10-04T00:03:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/10\/04\/fernando_sabino_ensinou\/"},"modified":"2015-10-23T16:38:02","modified_gmt":"2015-10-23T18:38:02","slug":"fernando_sabino_ensinou","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/fernando_sabino_ensinou\/","title":{"rendered":"Fernando Sabino ensinou"},"content":{"rendered":"\n<p> &#8220;No fim, tudo d\u00e1 certo. Se n\u00e3o deu, \u00e9 porque ainda  n\u00e3o chegou ao fim.\u201d  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;No fim, tudo d\u00e1 certo. Se n\u00e3o deu, \u00e9 porque ainda n\u00e3o chegou ao fim.\u201d<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-678","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=678"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/678\/revisions"}],"predecessor-version":[{"id":775,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/678\/revisions\/775"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}