{"id":6757,"date":"2012-02-24T06:50:00","date_gmt":"2012-02-24T08:50:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_cobica\/"},"modified":"2012-02-24T06:50:00","modified_gmt":"2012-02-24T08:50:00","slug":"a_cobica","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_cobica\/","title":{"rendered":"A cobi\u00e7a"},"content":{"rendered":"<p><strong><\/strong>  <\/p>\n<p>Muitos filmes disputam o Oscar. Alguns s\u00e3o gulosos. Concorrem em v\u00e1rias  categorias. <i>A inven\u00e7\u00e3o de Hugo Cabret <\/i>disputa 11 indica\u00e7\u00f5es.<i> Cavalo de  guerra <\/i>e <i>O homem que mudou o jogo<\/i>, seis. <i>Os descendentes<\/i> <i>e  Millennium,<\/i> cinco. <i>Hist\u00f3rias cruzadas<\/i>, quatro. E por a\u00ed va\u00ed.  Diretores, atores, produtores e tantos outros s\u00f3 miram um verbo. \u00c9 premiar. O  primeiro passo para atrair bons fluidos e a generosidade dos jurados \u00e9 conjugar  o triss\u00edlabo como mandam Cam\u00f5es, Machado e Pessoa.   <\/p>\n<p>Premiar joga no time de maquiar. Os dois se flexionam do mesmo jeitinho:  <i>eu premio (maquio), ele premia (maquia), n\u00f3s premiamos (maquiamos), eles  premiam (maquiam); eu premiei (maquiei), ele premiou (maquiou), n\u00f3s premiamos  (maquiamos), eles premiaram (maquiaram); que eu premie (maquie), ele premie  (maquie), n\u00f3s premiemos (maquiemos), eles premiem (maquiem).<\/i> Etc. e  tal. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muitos filmes disputam o Oscar. Alguns s\u00e3o gulosos. Concorrem em v\u00e1rias categorias. A inven\u00e7\u00e3o de Hugo Cabret disputa 11 indica\u00e7\u00f5es. Cavalo de guerra e O homem que mudou o jogo, seis. Os descendentes e Millennium, cinco. Hist\u00f3rias cruzadas, quatro. E por a\u00ed va\u00ed. Diretores, atores, produtores e tantos outros s\u00f3 miram um verbo. \u00c9 premiar. O primeiro passo para atrair bons fluidos e a generosidade [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6757","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6757"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6757\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}