{"id":6743,"date":"2012-02-23T12:00:00","date_gmt":"2012-02-23T14:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitora_pergunta-5\/"},"modified":"2015-11-13T10:25:22","modified_gmt":"2015-11-13T12:25:22","slug":"leitora_pergunta-5","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitora_pergunta-5\/","title":{"rendered":"Leitora pergunta"},"content":{"rendered":"\n<div><b> <\/p>\n<p><\/b> Li a frase: &#8220;Assertividade \u00e9 o caminho certo ao defender um ponto de  vista&#8221;. Pergunto: o uso de <i>assertividade<\/i> est\u00e1 correto?(Jo\u00e3o Le\u00e3o Lyrio) <\/p>\n<p><b>  <\/p>\n<p><\/b> Est\u00e1. <i>Assertividade<\/i> vem de <i>assertivo,<\/i> que vem de assser\u00e7\u00e3o.  Asser\u00e7\u00e3o, diz o dicion\u00e1rio, \u00e9 afirma\u00e7\u00e3o categ\u00f3rica. Ao ser assertiva, a pessoa  assume responsabilidade pelo que diz. Demonstra seguran\u00e7a, decis\u00e3o e firmeza nas  palavras e nas atitudes. Dizer &#8220;acho que ele vai jogar&#8221; soa indeciso. &#8220;Ele vai  jogar&#8221; \u00e9 determinado. &#8220;Vou tentar fazer o trabalho&#8221; \u00e9 jeito de se evadir.  Compare com &#8220;vou fazer o trabalho&#8221;. Vamos combinar? No mundo em que tantos se  negam a conjugar o verbo assumir, ser assertivo pega pra l\u00e1 de bem.  <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Li a frase: &#8220;Assertividade \u00e9 o caminho certo ao defender um ponto de vista&#8221;. Pergunto: o uso de assertividade est\u00e1 correto?(Jo\u00e3o Le\u00e3o Lyrio) Est\u00e1. Assertividade vem de assertivo, que vem de assser\u00e7\u00e3o. Asser\u00e7\u00e3o, diz o dicion\u00e1rio, \u00e9 afirma\u00e7\u00e3o categ\u00f3rica. Ao ser assertiva, a pessoa assume responsabilidade pelo que diz. Demonstra seguran\u00e7a, decis\u00e3o e firmeza nas palavras e nas atitudes. Dizer &#8220;acho que ele vai jogar&#8221; [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-6743","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6743"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6743\/revisions"}],"predecessor-version":[{"id":11451,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6743\/revisions\/11451"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}