{"id":673,"date":"2015-10-02T10:08:00","date_gmt":"2015-10-02T10:08:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/10\/02\/erramos-144\/"},"modified":"2015-11-25T19:45:58","modified_gmt":"2015-11-25T21:45:58","slug":"erramos-144","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-144\/","title":{"rendered":"Erramos"},"content":{"rendered":"<div>\n<p>\u201cO delegado Fernando C\u00e9sar Costa disse que houve op\u00e7\u00e3o de trabalhar em conjunto com a PF neste caso\u201d, escrevemos na p\u00e1g. 20. Viu? Pisamos de novo o pronome demonstrativo. O caso foi referido l\u00e1 na frente (opera\u00e7\u00e3o para desativar duas bananas de dinamite). Como remete a refer\u00eancia anterior, o <i>esse<\/i> pede passagem: <i>O delegado Fernando C\u00e9sar Costa disse que houve uma op\u00e7\u00e3o de trabalhar em conjunto com a PF nesse caso. <\/i><\/p>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO delegado Fernando C\u00e9sar Costa disse que houve op\u00e7\u00e3o de trabalhar em conjunto com a PF neste caso\u201d, escrevemos na p\u00e1g. 20. Viu? Pisamos de novo o pronome demonstrativo. O caso foi referido l\u00e1 na frente (opera\u00e7\u00e3o para desativar duas bananas de dinamite). Como remete a refer\u00eancia anterior, o esse pede passagem: O delegado Fernando C\u00e9sar Costa disse que houve uma op\u00e7\u00e3o de trabalhar em [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-673","post","type-post","status-publish","format-standard","hentry","category-erramos"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=673"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/673\/revisions"}],"predecessor-version":[{"id":11562,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/673\/revisions\/11562"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}