{"id":672,"date":"2015-10-02T00:00:00","date_gmt":"2015-10-02T00:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/10\/02\/diquinhas_uteis_3\/"},"modified":"2015-10-23T16:38:05","modified_gmt":"2015-10-23T18:38:05","slug":"diquinhas_uteis_3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diquinhas_uteis_3\/","title":{"rendered":"Diquinhas \u00fateis 3"},"content":{"rendered":"<p><b> <\/p>\n<p><\/b><b>Onomatopeia<\/b>   <\/p>\n<p>Au-au.   \u00c9 o c\u00e3o que late. Miau-miau. \u00c9 o gato que mia. Glu-glu. \u00c9 o peru que   gluglujeia. C\u00f3-c\u00f3. \u00c9 a galinha que cacareja. Chu\u00e1-chu\u00e1. \u00c9 a \u00e1gua que   cai. Tique-taque. \u00c9 o rel\u00f3gio que marca as horas.   <\/p>\n<p>As   palavras que reproduzem o som de vozes ou ru\u00eddos recebem nome pra l\u00e1  de  pomposo. \u00c9 onomatopeia. O adjetivo dela derivado tem duas formas \u2013   onomatopeico, onomatopaico. Ambas t\u00eam o mesmo significado. Escolha a que   lhe soar melhor.   <\/p>\n<p>Antes   da reforma ortogr\u00e1fica, as onomatopeias eram cheias de caprichos. Ora   se grafavam com h\u00edfen, ora sem. Agora todas pedem o tracinho:   bangue-bangue, bl\u00e1-bl\u00e1-bl\u00e1, c\u00f3-c\u00f3, pisca-pisca, tique-taque,   toque-toque, glu-glu, quem-quem, tim-tim.   <\/p>\n<p>Aten\u00e7\u00e3o: os derivados dispensam o h\u00edfen: gluglujear, cocoroc\u00f3. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Onomatopeia Au-au. \u00c9 o c\u00e3o que late. Miau-miau. \u00c9 o gato que mia. Glu-glu. \u00c9 o peru que gluglujeia. C\u00f3-c\u00f3. \u00c9 a galinha que cacareja. Chu\u00e1-chu\u00e1. \u00c9 a \u00e1gua que cai. Tique-taque. \u00c9 o rel\u00f3gio que marca as horas. As palavras que reproduzem o som de vozes ou ru\u00eddos recebem nome pra l\u00e1 de pomposo. \u00c9 onomatopeia. O adjetivo dela derivado tem duas formas \u2013 [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-672","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=672"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/672\/revisions"}],"predecessor-version":[{"id":781,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/672\/revisions\/781"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}