{"id":6603,"date":"2012-02-08T00:00:00","date_gmt":"2012-02-08T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/escrever_para_as_novas_midias\/"},"modified":"2012-02-08T00:00:00","modified_gmt":"2012-02-08T02:00:00","slug":"escrever_para_as_novas_midias","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/escrever_para_as_novas_midias\/","title":{"rendered":"Escrever para as novas m\u00eddias"},"content":{"rendered":"\n<p>Voc\u00ea escreve pra internet? Tem blogue, site, portal? Ou participa de redes  sociais? Ou navega palpitando aqui e ali? Num ou noutros casos, tenha uma  certeza. Mesmo assinado, o texto n\u00e3o \u00e9 seu. Ele cria asas e pousa em destinos  diferentes do imaginado. Com o escrito, pois, todo o cuidado \u00e9 pouco. Seu recado  se torna seu cart\u00e3o de visita.  <\/p>\n<p>Se voc\u00ea for profissional, ter\u00e1 de mudar a cabe\u00e7a. Guarde isto: voc\u00ea e o  internauta s\u00e3o colaboradores. Coment\u00e1rios viram pauta, not\u00edcia, amplia\u00e7\u00e3o de  conte\u00fado. Fotos encaminhadas por desconhecidos ilustram mat\u00e9rias, ganham  chamadas ou entram em podcasts. V\u00eddeos e \u00e1udios t\u00eam destino similar. \u00c9 um  admir\u00e1vel mundo novo. Como lidar com ele? Observe:   <\/p>\n<p>1. <b>Portugu\u00eas correto<\/b>. N\u00e3o caia na esparrela de que a pressa justifica  trope\u00e7os de ortografia, flex\u00f5es, concord\u00e2ncias e reg\u00eancias. Erros pegam mal.  Desacreditam o conte\u00fado, o escritor, o blogue, o portal.  <\/p>\n<p>2. <b>Textos curtos<\/b>. A not\u00edcia n\u00e3o deve ultrapassar o tamanho da tela.  Links aprofundam o conte\u00fado.   <\/p>\n<p>3. <b>Senten\u00e7as declarativas com apenas uma ideia<\/b>. Compare<i>: O senador  chegou ao plen\u00e1rio por volta das 14h30 na expectativa de que faria o  pronunciamento meia hora depois, mas frustrou-se porque at\u00e9 as 17h n\u00e3o tinha  sido chamado.<\/i> (O per\u00edodo tem tr\u00eas ideias.) Melhor desmembr\u00e1-las: <i>O  senador chegou ao plen\u00e1rio por volta das 14h30 na expectativa de fazer o  pronunciamento meia hora depois. Frustrou-se. At\u00e9 as 17h n\u00e3o tinha sido  chamado.<\/i>  <\/p>\n<p>4. <b>Frases curtas e, sempre que poss\u00edvel, bem-humoradas<\/b>. Cace e casse  sem piedade ger\u00fandios, qu\u00eas e palavras cuja fun\u00e7\u00e3o \u00e9 enfeitar. Curso em n\u00edvel de  p\u00f3s-gradua\u00e7\u00e3o? \u00c9 curso de p\u00f3s-gradua\u00e7\u00e3o. Caixa contendo 20 bombons? \u00c9 caixa com  20 bombons. Doen\u00e7a de natureza heredit\u00e1ria? \u00c9 doen\u00e7a heredit\u00e1ria.  <\/p>\n<p>5. <b>Verbos fortes de prefer\u00eancia na voz ativa<\/b>. Com eles, voc\u00ea escreve  textos vivos, arejados e alegres. Em fez de <i>fazer o trajeto<\/i>, prefira  <i>percorrer o trajeto<\/i>. Em lugar de <i>p\u00f4r o dinheiro<\/i> <i>no banco<\/i>,  que tal <i>depositar o dinheiro<\/i>? N\u00e3o diga o segredo. Revele o segredo.  <\/p>\n<p>6. <b>Declara\u00e7\u00f5es diretas<\/b>. Entre logo no assunto. Ningu\u00e9m merece come\u00e7ar  a leitura com enrola\u00e7\u00e3o como esta: Como todo mundo sabe, o processo eleitoral  brasileiro \u00e9 o mais moderno do mundo. (Ora, se todo mundo sabe, pra que dizer?  N\u00e3o encha lingui\u00e7a: O processo eleitoral brasileiro \u00e9 o mais moderno do  mundo.)  <\/p>\n<p>7. <b>Enunciados concretos<\/b>. Palavras abstratas e gen\u00e9ricas s\u00e3o pragas que  tornam o enunciado longo, obscuro e dif\u00edcil de ler. Compare: <i>O processo  empregado na busca dos melhores profissionais encontrados no mercado constitui  tarefa \u00e1rdua que exige muito tempo<\/i>. Melhor: <i>A sele\u00e7\u00e3o dos melhores  profissionais exige tempo e esfor\u00e7o. <\/i>  <\/p>\n<p>8. <b>Facilidade de leitura<\/b>. Pesquisas provam que 80% das pessoas acessam  a internet sobretudo em busca de informa\u00e7\u00e3o. Quem lhes satisfaz a expectativa  ganha ponto. Conquista-as. Siga a dica: menor \u00e9 melhor. Se f\u00e1cil, juntam-se  tamanho e rapidez. Oba!  <\/p>\n<p>9. <b>Foco nas necessidades e h\u00e1bito dos visitantes<\/b>. O internauta, vimosem post anterior, tem marcas registradas. Ele \u00e9 infiel, inconstante,  apressado, arisco, cr\u00edtico, exigente, multim\u00eddia, proativo.   <\/p>\n<p>10. <b>Respeito ao leitor<\/b>. N\u00e3o o subestime. Ele percebe quando encontra  uma p\u00e1gina incompleta ou feita nas coxas.  <\/p>\n<p>11. <b>Narrativa sedutora<\/b>. Se os fornecedores de conte\u00fado s\u00e3o os mesmos,  como oferecer algo mais para cativar o visitante? A sa\u00edda: trabalhar bem a  informa\u00e7\u00e3o, explorar ao m\u00e1ximo os recursos da hiperm\u00eddia. Al\u00e9m do texto,  recorrer a \u00e1udios, gr\u00e1ficos, v\u00eddeos, links. Ou \u00e0 combina\u00e7\u00e3o de todos.<b> &nbsp;<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea escreve pra internet? Tem blogue, site, portal? Ou participa de redes sociais? Ou navega palpitando aqui e ali? Num ou noutros casos, tenha uma certeza. Mesmo assinado, o texto n\u00e3o \u00e9 seu. Ele cria asas e pousa em destinos diferentes do imaginado. Com o escrito, pois, todo o cuidado \u00e9 pouco. Seu recado se torna seu cart\u00e3o de visita. Se voc\u00ea for profissional, ter\u00e1 [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6603","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6603"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6603\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}