{"id":6598,"date":"2012-05-30T10:30:00","date_gmt":"2012-05-30T13:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-811\/"},"modified":"2015-11-12T16:26:35","modified_gmt":"2015-11-12T18:26:35","slug":"erramos-811","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-811\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>Gerson Menezes escreve: &#8220;Saiu na p\u00e1g. 30 do  <b>Correio<\/b> de 30.5: `A cada dia que Fernanda pega um \u00f4nibus em Bras\u00edlia, ela  se surpreende com a qualidade deles, comparada \u00e0 outras capitais\u00b4. Falta ou  sobra algo, n\u00e3o?&#8221; O leitor tem raz\u00e3o. Compara-se a qualidade dos \u00f4nibus de  Bras\u00edlia com (a qualidade) dos \u00f4nibus de outras capitais. Melhor corrigir: <i>\u2026  ela se surpreende com a qualidade deles comparada \u00e0 dos de outras  capitais.<\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gerson Menezes escreve: &#8220;Saiu na p\u00e1g. 30 do Correio de 30.5: `A cada dia que Fernanda pega um \u00f4nibus em Bras\u00edlia, ela se surpreende com a qualidade deles, comparada \u00e0 outras capitais\u00b4. Falta ou sobra algo, n\u00e3o?&#8221; O leitor tem raz\u00e3o. Compara-se a qualidade dos \u00f4nibus de Bras\u00edlia com (a qualidade) dos \u00f4nibus de outras capitais. Melhor corrigir: \u2026 ela se surpreende com a qualidade [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-6598","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6598"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6598\/revisions"}],"predecessor-version":[{"id":9973,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6598\/revisions\/9973"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}