{"id":658,"date":"2015-09-28T19:20:00","date_gmt":"2015-09-28T19:20:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/09\/28\/a_terra_balancou_la_e_ca_2\/"},"modified":"2015-10-23T16:44:03","modified_gmt":"2015-10-23T18:44:03","slug":"a_terra_balancou_la_e_ca_2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_terra_balancou_la_e_ca_2\/","title":{"rendered":"A terra balan\u00e7ou l\u00e1 e c\u00e1 2"},"content":{"rendered":"<p><b> <\/p>\n<p><\/b><b>G\u00eanero<\/b><b> <\/p>\n<p><\/b>  H\u00e1 terremotos e terremotos. Quando o epicentro \u00e9 no mar, ondas gigantescas se levantam. O horror se chama tsunami. Ao se referir a ele, um cuidado se imp\u00f5e: respeitar o g\u00eanero da palavra. Ela \u00e9 masculina sim, senhores.  <b>&nbsp;<\/b>  <b>Olhinhos puxados<\/b>  &nbsp;  Nem s\u00f3 de sushi e saqu\u00ea vive o japon\u00eas. Exporta\u00e7\u00f5es  tamb\u00e9m fazem a festa. Entre elas, voc\u00e1bulos. A l\u00edngua do povo amarelo de cabelos lisos e olhinhos puxados enriqueceu o l\u00e9xico  portugu\u00eas. Uma das contribui\u00e7\u00f5es: tsunami. A palavra tem duas partes.  Uma: <i>tsu<\/i>. As tr\u00eas letrinhas querem dizer <i>mar.<\/i> A outra: <i>nami<\/i>, que significa<i> ondas<\/i>. Em bom portugu\u00eas: tsunami s\u00e3o ondas mar\u00edtimas gigantes.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>G\u00eanero H\u00e1 terremotos e terremotos. Quando o epicentro \u00e9 no mar, ondas gigantescas se levantam. O horror se chama tsunami. Ao se referir a ele, um cuidado se imp\u00f5e: respeitar o g\u00eanero da palavra. Ela \u00e9 masculina sim, senhores. &nbsp; Olhinhos puxados &nbsp; Nem s\u00f3 de sushi e saqu\u00ea vive o japon\u00eas. Exporta\u00e7\u00f5es tamb\u00e9m fazem a festa. Entre elas, voc\u00e1bulos. A l\u00edngua do povo amarelo [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-658","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=658"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/658\/revisions"}],"predecessor-version":[{"id":794,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/658\/revisions\/794"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}