{"id":651,"date":"2015-09-18T17:41:00","date_gmt":"2015-09-18T17:41:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/09\/18\/erramos-139\/"},"modified":"2015-11-12T12:01:15","modified_gmt":"2015-11-12T14:01:15","slug":"erramos-139","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-139\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>\u201cO ministro Levy  e Nelson Barbosa, do Planejamento: apesar das cr\u00edticas, Executivo n\u00e3o tem plano  B para acionar, caso o pacote fiscal seja rejeitado\u201d, escrevemos na legenda da  p\u00e1g. 6. Viu? H\u00e1 faltas e sobras. Falta artigo. S\u00f3 h\u00e1 um Executivo. O artigo se  imp\u00f5e. Sobra v\u00edrgula. A ora\u00e7\u00e3o adverbial est\u00e1 no lugar dela. Dispensa a  bengalinha. Melhor: <i>O ministro Levy e Nelson Barbosa, do Planejamento: apesar  das cr\u00edticas, o Executivo n\u00e3o tem plano B para acionar caso o pacote fiscal seja  rejeitado. <\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO ministro Levy e Nelson Barbosa, do Planejamento: apesar das cr\u00edticas, Executivo n\u00e3o tem plano B para acionar, caso o pacote fiscal seja rejeitado\u201d, escrevemos na legenda da p\u00e1g. 6. Viu? H\u00e1 faltas e sobras. Falta artigo. S\u00f3 h\u00e1 um Executivo. O artigo se imp\u00f5e. Sobra v\u00edrgula. A ora\u00e7\u00e3o adverbial est\u00e1 no lugar dela. Dispensa a bengalinha. Melhor: O ministro Levy e Nelson Barbosa, do [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-651","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=651"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/651\/revisions"}],"predecessor-version":[{"id":801,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/651\/revisions\/801"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}