{"id":6500,"date":"2012-01-30T13:00:00","date_gmt":"2012-01-30T15:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/dilma_em_cuba\/"},"modified":"2012-01-30T13:00:00","modified_gmt":"2012-01-30T15:00:00","slug":"dilma_em_cuba","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/dilma_em_cuba\/","title":{"rendered":"Dilma em Cuba"},"content":{"rendered":"\n<div><b>  <\/p>\n<p><\/b>  <\/p>\n<p>Viagens presidenciais \u00e0 bela ilha do Caribe n\u00e3o passam despercebidas. Merecem  p\u00e1ginas de jornais. Excitam comentaristas. Dividem opini\u00f5es. Ocupam espa\u00e7os  generosos nos telejornais. Em suma: chamam mais a aten\u00e7\u00e3o que melancia pendurada  no pesco\u00e7o.  <\/p>\n<p>A visita de Dilma segue o script. Equipes encarregadas de cobrir o evento  apresentaram pautas criativas, fizeram entrevistas, descobriram hist\u00f3rias  tr\u00e1gicas e divertidas no mais de meio s\u00e9culo de ditadura dos irm\u00e3os Castro. Mas  um pormenor manteve-se teimoso. Trata-se de grampinho pra l\u00e1 de intruso. N\u00e3o  faltou quem escrevesse &#8220;Dilma vai \u00e0 Cuba&#8221;, &#8220;Dilma chega \u00e0 Cuba&#8221;. Valha-nos,  Deus!   <\/p>\n<p>Nome de pa\u00edses, estados e cidades s\u00e3o caprichosos. Ora pedem artigo. Ora  esnobam-no. Por isso, \u00e0s vezes exigem crase. \u00c0s vezes n\u00e3o. Como saber? H\u00e1 um  truque. Construa a frase com o verbo ir. Depois, substitua-o por voltar. Por  fim, siga o conselho da quadrinha:  &nbsp;<i> Se, ao voltar, volto da,  crase no a.  Se, ao voltar, volto de,  crase pra qu\u00ea? <\/i>  <\/p>\n<p>Teste o versinho. Com ou sem crase?   <\/p>\n<p>Dilma vai a Cuba. Dilma volta de Cuba.   <\/p>\n<p>(Se, ao voltar, volta de, crase pra qu\u00ea?)  <\/p>\n<p>Dilma vai \u00e0 Cuba de Fidel e Ra\u00fal Castro. Dilma volta da Cuba de Fifel e Ra\u00fal Castro.  <\/p>\n<p>(Se, ao voltar, volta da, crase no a.)   <\/p>\n<p>Mais exemplos:  <\/p>\n<p>Vou a Paris, a Londres e a Roma. Volto de Paris, de Londres e de Roma (crase  pra qu\u00ea?).   <\/p>\n<p>Vou \u00e0 Paris da alta costura, \u00e0 Londres do fog e \u00e0 Roma dos c\u00e9zares. Volto da  Paris da alta costura, da Londres do fog e da Roma dos C\u00e9zares (volto da, crase no a). <\/p>\n<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Viagens presidenciais \u00e0 bela ilha do Caribe n\u00e3o passam despercebidas. Merecem p\u00e1ginas de jornais. Excitam comentaristas. Dividem opini\u00f5es. Ocupam espa\u00e7os generosos nos telejornais. Em suma: chamam mais a aten\u00e7\u00e3o que melancia pendurada no pesco\u00e7o. A visita de Dilma segue o script. Equipes encarregadas de cobrir o evento apresentaram pautas criativas, fizeram entrevistas, descobriram hist\u00f3rias tr\u00e1gicas e divertidas no mais de meio s\u00e9culo de ditadura dos [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6500","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6500"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6500\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}