{"id":65,"date":"2015-01-22T00:05:00","date_gmt":"2015-01-22T00:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/01\/22\/a_internet_e_inocente\/"},"modified":"2015-10-23T17:09:06","modified_gmt":"2015-10-23T19:09:06","slug":"a_internet_e_inocente","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_internet_e_inocente\/","title":{"rendered":"A internet \u00e9 inocente"},"content":{"rendered":"<p><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">    DAD SQUARISI <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">     <\/p>\n<p>Mais de meio milh\u00e3o de zeros no Enem? A not\u00edcia surpreendeu. N\u00e3o pela nota. Mas pela quantidade de reprovados. Explica\u00e7\u00f5es ca\u00edram do c\u00e9u e saltaram do inferno. Entre elas, a falta de familiaridade com o tema, a fuga do tema, a incompreens\u00e3o do tema. Muitos responsabilizaram a internet pela calamidade. A rede teria o poder de deseducar. Quem escrevia deixou de escrever.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">     <\/p>\n<p>Ser\u00e1? Jornais, revistas, sites, blogues est\u00e3o ao alcance de um toque. Ningu\u00e9m precisa ir \u00e0 banca comprar a informa\u00e7\u00e3o. Cartas viraram lembran\u00e7as de tempos idos e vividos. Deram vez a mensagens eletr\u00f4nicas que v\u00e3o e v\u00eam em segundos. O Google relegou ao esquecimento enciclop\u00e9dias que h\u00e1 pouco enchiam as estantes de orgulho. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p>Em bom portugu\u00eas: mudamos o suporte, mas continuamos a ler e a escrever. Em vez de papel, a tela. Culpar o suporte pelo fracasso da mo\u00e7ada \u00e9 baratear o problema. O buraco \u00e9 mais embaixo. L\u00ea mal e escreve mal quem nunca aprendeu a ler bem e a escrever bem. O retrato exibido pelo Enem \u00e9 obra da escola. N\u00e3o entender o tema constitui problema de leitura. N\u00e3o conseguir desenvolv\u00ea-lo, de escrita. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">     <\/p>\n<p>Crian\u00e7a \u00e9 curiosa. Adora aprender. Estimula-se com desafios. Enfrenta embates. Mas \u2026 cad\u00ea? Encontra salas de aula do s\u00e9culo 19, professores sem compromisso, material did\u00e1tico modernoso \u2014 sem foco e n\u00e3o raras vezes com erros grosseiros, confunde em vez de ensinar. Com internet ou sem internet, o resultado n\u00e3o muda. Sem o dom\u00ednio das habilidades de leitura e escrita \u2014 fruto de estudo, disciplina e treino \u2014 esperar nota azul nesse cen\u00e1rio \u00e9 ignor\u00e2ncia, m\u00e1-f\u00e9 ou ingenuidade.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">     <\/p>\n<p>Somos poliglotas na nossa l\u00edngua. \u201cN\u00e3o falamos portugu\u00eas\u201d, ensinou Saramago. \u201cFalamos l\u00ednguas em portugu\u00eas.\u201d A m\u00e3e de todas elas \u2014 a norma culta \u2014 abre o caminho da liberdade. Com tr\u00e2nsito nas possibilidades do idioma, torna-se poss\u00edvel escolher. G\u00edrias, regionalismos, estrangeirismos, abreviaturas, internet\u00eas &amp; cia. ilimitada t\u00eam vez no universo da comunica\u00e7\u00e3o. Us\u00e1-los no contexto correto pressup\u00f5e conhecimento \u2014 o saber que a escola sonega aos brasileiros. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">     <\/p>\n<p>(artigo publicado no Correio Braziliense de hoje)<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>DAD SQUARISI Mais de meio milh\u00e3o de zeros no Enem? A not\u00edcia surpreendeu. N\u00e3o pela nota. Mas pela quantidade de reprovados. Explica\u00e7\u00f5es ca\u00edram do c\u00e9u e saltaram do inferno. Entre elas, a falta de familiaridade com o tema, a fuga do tema, a incompreens\u00e3o do tema. Muitos responsabilizaram a internet pela calamidade. A rede teria o poder de deseducar. Quem escrevia deixou de escrever. Ser\u00e1? [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-65","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":1380,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/65\/revisions\/1380"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}