{"id":6469,"date":"2012-05-22T13:00:00","date_gmt":"2012-05-22T16:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/refresque_a_memoria\/"},"modified":"2012-05-22T13:00:00","modified_gmt":"2012-05-22T16:00:00","slug":"refresque_a_memoria","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/refresque_a_memoria\/","title":{"rendered":"Refresque a mem\u00f3ria"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">       <\/p>\n<p>     <\/b> A tireoide est\u00e1 em cartaz. A semana \u00e9 dedicada a ela. Vale o  lembrete: a reforma ortogr\u00e1fica cassou o acento do ditongo <i>oi<\/i> que aparece  nas parox\u00edtonas: heroico, paranoico, joia, jiboia. E, claro,  tireoide.        <\/p>\n<p>Olho  vivo! A reforma s\u00f3 passou a tesoura nos acentos das  parox\u00edtonas. As  ox\u00edtonas e os monoss\u00edlabos t\u00f4nicos mant\u00eam o grampinho sem   constrangimentos: <i>her\u00f3i, len\u00e7\u00f3is, constr\u00f3i, d\u00f3i<\/i>.<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">       &nbsp;<\/b>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tireoide est\u00e1 em cartaz. A semana \u00e9 dedicada a ela. Vale o lembrete: a reforma ortogr\u00e1fica cassou o acento do ditongo oi que aparece nas parox\u00edtonas: heroico, paranoico, joia, jiboia. E, claro, tireoide. Olho vivo! A reforma s\u00f3 passou a tesoura nos acentos das parox\u00edtonas. As ox\u00edtonas e os monoss\u00edlabos t\u00f4nicos mant\u00eam o grampinho sem constrangimentos: her\u00f3i, len\u00e7\u00f3is, constr\u00f3i, d\u00f3i. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6469","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6469"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6469\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}