{"id":6454,"date":"2012-09-26T14:04:00","date_gmt":"2012-09-26T17:04:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/desacordo_ortografico\/"},"modified":"2012-09-26T14:04:00","modified_gmt":"2012-09-26T17:04:00","slug":"desacordo_ortografico","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/desacordo_ortografico\/","title":{"rendered":"(Des)acordo ortogr\u00e1fico"},"content":{"rendered":"\n<p>  <a href=\"http:\/\/ilcao.cedilha.net\/?p=7304\">http:\/\/ilcao.cedilha.net\/?p=7304<\/a>    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>http:\/\/ilcao.cedilha.net\/?p=7304<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6454","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6454"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6454\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}