{"id":644,"date":"2015-09-16T09:09:00","date_gmt":"2015-09-16T09:09:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/09\/16\/a_que_horas_1\/"},"modified":"2015-10-23T16:44:08","modified_gmt":"2015-10-23T18:44:08","slug":"a_que_horas_1","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_que_horas_1\/","title":{"rendered":"A que horas? (1)"},"content":{"rendered":"<p>\u201cA coisa est\u00e1 feia\u201d, disse  Roberto Barreto de si para si. Ele lia not\u00edcia pra l\u00e1 de alvissareira. Pel\u00edcula  brasileira vai disputar o Oscar de melhor filme estrangeiro. O orgulho tomou  ducha fria ao ver o nome da obra \u2014 <i>Que horas ela volta<\/i>? Depois do choque,  o leitor formulou pergunta indignada: \u201cCom erro&nbsp;lingu\u00edstico  escancarado no cartaz, a produ\u00e7\u00e3o verde-amarela merece a estatueta?\u201d  <\/p>\n<p>Rangel Cavalcante foi al\u00e9m.  Em mensagem ao amigo Paulo Jos\u00e9 Cunha, escreveu: \u201cUm erro de portugu\u00eas pode  prejudicar nossa imagem no exterior. O Brasil investe mais de R$ 1,5 milh\u00e3o, e o  filme que pode nos representar em Hollywood exibe t\u00edtulo que desrespeita a  l\u00edngua. Como \u00e9 que pode? Como se explica o descuido?\u201d  <\/p>\n<p> <b>A  resposta<\/b>  <\/p>\n<p> Tanta&nbsp;indigna\u00e7\u00e3o  se explica. A l\u00edngua \u00e9 o cart\u00e3o de visita do pa\u00eds. Com o erro, ficamos mal na  foto. Damos atestado de m\u00e1 escola. Ou, como diziam as vov\u00f3s de antigamente,  provamos que nosso prim\u00e1rio foi malfeito.  <\/p>\n<p>Em tempos idos e vividos, o  professor ensinava e o aluno aprendia. Ao deixar as salas de aula, a meninada  sabia a li\u00e7\u00e3o na ponta da l\u00edngua: a indica\u00e7\u00e3o de horas tem manhas. Uma delas \u2014 a  exig\u00eancia de certas companhias. No caso, a preposi\u00e7\u00e3o <i>a<\/i>. O nome do filme  encheria os cidad\u00e3os de orgulho se fosse este: <i>A que horas ela volta? <\/i>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cA coisa est\u00e1 feia\u201d, disse Roberto Barreto de si para si. Ele lia not\u00edcia pra l\u00e1 de alvissareira. Pel\u00edcula brasileira vai disputar o Oscar de melhor filme estrangeiro. O orgulho tomou ducha fria ao ver o nome da obra \u2014 Que horas ela volta? Depois do choque, o leitor formulou pergunta indignada: \u201cCom erro&nbsp;lingu\u00edstico escancarado no cartaz, a produ\u00e7\u00e3o verde-amarela merece a estatueta?\u201d Rangel Cavalcante [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-644","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=644"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/644\/revisions"}],"predecessor-version":[{"id":808,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/644\/revisions\/808"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}