{"id":643,"date":"2015-09-16T08:00:00","date_gmt":"2015-09-16T08:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/09\/16\/a_que_horas_2\/"},"modified":"2015-10-23T16:45:31","modified_gmt":"2015-10-23T18:45:31","slug":"a_que_horas_2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_que_horas_2\/","title":{"rendered":"A que horas? (2)"},"content":{"rendered":"<p><b> <\/p>\n<p><\/b><b>Preposi\u00e7\u00e3o  <\/b>   <\/p>\n<p> A preposi\u00e7\u00e3o n\u00e3o aparece s\u00f3  na pergunta. Tamb\u00e9m est\u00e1 presente na resposta. Veja:  <i>  <\/p>\n<p><\/i><i>A que horas ela chega? Ela  chega \u00e0s 10 horas.<\/i> <i>A que horas a aula come\u00e7a?  A aula come\u00e7a ao meio-dia.<\/i> <i>A que horas Maria viajou?  Ela viajou \u00e0s 11 horas da noite.<\/i>   <\/p>\n<p> <b>Artigo<\/b>   <\/p>\n<p> O artigo \u00e9 tamb\u00e9m presen\u00e7a  obrigat\u00f3ria na indica\u00e7\u00e3o de horas. Da\u00ed a crase. O encontro da preposi\u00e7\u00e3o  <i>a<\/i> com o artigo <i>a<\/i> resulta no casadinho <i>\u00e0<\/i>. Duvida? Ent\u00e3o  apele para o tira-teima. Substitua a hora por <i>meio-dia<\/i>. Se no troca-troca  der <i>ao<\/i>, sinal de uni\u00e3o insepar\u00e1vel. Quer ver? <i>  <\/p>\n<p><\/i><i>Chego \u00e0s duas horas.  (Chego ao meio-dia.)<\/i> <i>Trabalho das 2h \u00e0s 4h.  (Trabalho das 2h ao meio-dia.)<\/i> <i>Ela viajou \u00e0s 11h da  noite. (Ela viajou ao meio-dia.)<\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preposi\u00e7\u00e3o A preposi\u00e7\u00e3o n\u00e3o aparece s\u00f3 na pergunta. Tamb\u00e9m est\u00e1 presente na resposta. Veja: A que horas ela chega? Ela chega \u00e0s 10 horas. A que horas a aula come\u00e7a? A aula come\u00e7a ao meio-dia. A que horas Maria viajou? Ela viajou \u00e0s 11 horas da noite. Artigo O artigo \u00e9 tamb\u00e9m presen\u00e7a obrigat\u00f3ria na indica\u00e7\u00e3o de horas. Da\u00ed a crase. O encontro da preposi\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-643","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=643"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/643\/revisions"}],"predecessor-version":[{"id":809,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/643\/revisions\/809"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}