{"id":6395,"date":"2012-05-16T00:00:00","date_gmt":"2012-05-16T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/com_carinho\/"},"modified":"2012-05-16T00:00:00","modified_gmt":"2012-05-16T03:00:00","slug":"com_carinho","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/com_carinho\/","title":{"rendered":"Com carinho"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">      <\/p>\n<p>   <\/b>  <\/p>\n<p>Estamos em ano eleitoral. Iniciativas populares s\u00e3o pra l\u00e1  de bem-vindas. Se contemplarem crian\u00e7as, ganham o dobro de aplausos. \u00c9 o caso do  Brasil Carinhoso. Trata-se da amplia\u00e7\u00e3o do Bolsa Fam\u00edlia que beneficia meninos e  meninas de at\u00e9 6 anos. O programa complementa a renda das fam\u00edlias para que  ultrapasse o limiar mensal de R$ 70 por pessoa. A medida&nbsp;exigiu dois cuidados lingu\u00edsticos.        <\/p>\n<p>Um: o tal <i>de zero a seis anos<\/i>. O ano come\u00e7a a contar  com 365 dias. Melhor ficar com &#8220;crian\u00e7as  de at\u00e9 6 anos&#8221;.        <\/p>\n<p>O&nbsp;outro: a grafia de  carinhoso. Por que o <b>s<\/b>? O poliss\u00edlabo segue regra antiga como o rascunho  da <i>B\u00edblia<\/i>. Adjetivo derivado de substantivo abstrato se escreve com      <i>s<\/i>: <i>carinho (carinhoso), gosto (gostoso), estudo (estudioso), d\u00e1diva  (dadivoso), medo (medroso); bondade (bondoso), amor (amoroso). <\/i>       <\/p>\n<p>Etc. Etc. Etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos em ano eleitoral. Iniciativas populares s\u00e3o pra l\u00e1 de bem-vindas. Se contemplarem crian\u00e7as, ganham o dobro de aplausos. \u00c9 o caso do Brasil Carinhoso. Trata-se da amplia\u00e7\u00e3o do Bolsa Fam\u00edlia que beneficia meninos e meninas de at\u00e9 6 anos. O programa complementa a renda das fam\u00edlias para que ultrapasse o limiar mensal de R$ 70 por pessoa. A medida&nbsp;exigiu dois cuidados lingu\u00edsticos. Um: o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6395","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6395"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6395\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}