{"id":628,"date":"2015-09-05T00:00:00","date_gmt":"2015-09-05T00:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/09\/05\/diquinhas_de_portugues_62\/"},"modified":"2015-12-10T10:12:51","modified_gmt":"2015-12-10T12:12:51","slug":"diquinhas_de_portugues_62","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diquinhas_de_portugues_62\/","title":{"rendered":"Diquinhas de Portugu\u00eas 61"},"content":{"rendered":"<p>Orfeu, o m\u00fasico<\/p>\n<p>Orfeu fazia poesia. Cantava como anjo. Tocava lira como ningu\u00e9m. Gente e bichos n\u00e3o resistiam aos encantos do artista. Ao ouvi-lo, os animais selvagens ficavam mansinhos, mansinhos. As plantas se viravam na dire\u00e7\u00e3o dele. As pessoas paravam, maravilhadas.<\/p>\n<p>Um dia, Orfeu conheceu Eur\u00eddice. Os dois se casaram. Num domingo, Eur\u00eddice passeava no campo. Tirou o sapato e \u2026 ops! Uma cobra a picou. Ela morreu. O marido, muito triste, foi procur\u00e1-la no reino dos mortos. Com o belo canto, comoveu Hades, o deus das sombras. Pediu a ele que a libertasse.<\/p>\n<p>Hades aceitou, mas imp\u00f4s uma condi\u00e7\u00e3o: \u201cAnde na frente da sua mulher. N\u00e3o olhe pra tr\u00e1s. S\u00f3 se volte quando chegar \u00e0 Terra\u201d. Os dois andaram muito. Ele na frente, ela atr\u00e1s. Quando estavam quase chegando, bateu a d\u00favida. Eur\u00eddice o estaria seguindo? Orfeu olhou pra tr\u00e1s. Teve tempo de ver Eur\u00eddice desaparecer. Ela morreu de novo. Para sempre.<\/p>\n<p><b>Inferno<\/b><\/p>\n<p>Para os crist\u00e3os, inferno \u00e9 o contr\u00e1rio de c\u00e9u. O c\u00e9u \u00e9 o para\u00edso. Todos querem ir pra l\u00e1. Mas s\u00f3 os bons v\u00e3o. O inferno \u00e9 lugar de sofrimento. Ningu\u00e9m quer saber dele. Para os gregos, o inferno \u00e9 o reino dos mortos. Pra l\u00e1 v\u00e3o todas as pessoas que morrem. N\u00e3o importa se s\u00e3o boas ou m\u00e1s.<\/p>\n<p><b>O chefe<\/b><\/p>\n<p>Para os crist\u00e3os, quem manda no inferno \u00e9 \u2026&#8230;&#8230;&#8230;&#8230;&#8230;. Para os gregos \u00e9 \u2026&#8230;&#8230;&#8230;&#8230;&#8230;..<\/p>\n<p>&nbsp;<\/p>\n<p><b>Acento<\/b><\/p>\n<p>Eur\u00eddice tem acento porque \u00e9 proparox\u00edtona. A s\u00edlaba fortona \u00e9 a antepen\u00faltima. Aparece sempre acentuada: Eu-<b>r\u00ed<\/b>-di-ce.<\/p>\n<p><b>Ca\u00e7a-palavras<\/b><\/p>\n<p>Encontre as outras proparox\u00edtonas que aparecem no texto: HADESINFERNO D\u00daVIDAMORTOS ORFEUM\u00daSICOS OLHARM\u00daSICAIS<\/p>\n<p><b>Resposta<\/b> diabo, Hades Ca\u00e7a-palavras: d\u00favida, m\u00fasico, m\u00fasica<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orfeu, o m\u00fasico Orfeu fazia poesia. Cantava como anjo. Tocava lira como ningu\u00e9m. Gente e bichos n\u00e3o resistiam aos encantos do artista. Ao ouvi-lo, os animais selvagens ficavam mansinhos, mansinhos. As plantas se viravam na dire\u00e7\u00e3o dele. As pessoas paravam, maravilhadas. Um dia, Orfeu conheceu Eur\u00eddice. Os dois se casaram. Num domingo, Eur\u00eddice passeava no campo. Tirou o sapato e \u2026 ops! Uma cobra a [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62,1],"tags":[],"class_list":["post-628","post","type-post","status-publish","format-standard","hentry","category-diquinhas","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=628"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/628\/revisions"}],"predecessor-version":[{"id":11647,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/628\/revisions\/11647"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}