{"id":6245,"date":"2012-05-07T10:00:00","date_gmt":"2012-05-07T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta_2-15\/"},"modified":"2015-11-13T10:22:57","modified_gmt":"2015-11-13T12:22:57","slug":"leitor_pergunta_2-15","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta_2-15\/","title":{"rendered":"Leitor pergunta 2"},"content":{"rendered":"<p><strong style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><strong style=\"font-family: Verdana,Arial,Helvetica,sans-serif;font-weight: normal\"> Gostaria que voc\u00ea me explicasse o significado de <i>o n\u00e3o menos  famoso, o n\u00e3o menos rico, o n\u00e3o menos charmoso. <\/i> (Antonio Andrade) <\/p>\n<p><\/strong> <b><\/b> <\/strong> <\/p>\n<p>&#8220;O n\u00e3o menos famoso&#8221; quer dizer &#8220;o igualmente famoso&#8221;: <i>Neymar  atraiu a aten\u00e7\u00e3o da imprensa e do p\u00fablico. O n\u00e3o menos famoso Loco Abreu foi  tamb\u00e9m assediado por jornalistas e torcedores. <\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gostaria que voc\u00ea me explicasse o significado de o n\u00e3o menos famoso, o n\u00e3o menos rico, o n\u00e3o menos charmoso. (Antonio Andrade) &#8220;O n\u00e3o menos famoso&#8221; quer dizer &#8220;o igualmente famoso&#8221;: Neymar atraiu a aten\u00e7\u00e3o da imprensa e do p\u00fablico. O n\u00e3o menos famoso Loco Abreu foi tamb\u00e9m assediado por jornalistas e torcedores.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-6245","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=6245"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6245\/revisions"}],"predecessor-version":[{"id":11364,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/6245\/revisions\/11364"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=6245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=6245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=6245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}