{"id":5997,"date":"2011-12-07T00:02:00","date_gmt":"2011-12-07T02:02:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta_1-11\/"},"modified":"2015-11-13T10:23:11","modified_gmt":"2015-11-13T12:23:11","slug":"leitor_pergunta_1-11","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta_1-11\/","title":{"rendered":"Leitor pergunta 1"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p><\/b>  <\/p>\n<p>Detalhe \u00e9 galicismo? (A. Toledo Ferreira) <\/p>\n<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><\/b> Galicismo \u00e9 palavra, constru\u00e7\u00e3o ou locu\u00e7\u00e3o da l\u00edngua francesa tomada de  empr\u00e9stimo por outra l\u00edngua. O portugu\u00eas n\u00e3o faz cerim\u00f4nia. Enriquece o l\u00e9xico  com contribui\u00e7\u00f5es de diferentes nacionalidades. Do \u00e1rabe, incorporou \u00e1lcool,  algod\u00e3o, bazar. Do alem\u00e3o, campe\u00e3o, blitz. Do italiano, fiasco, pizza, carnaval.  Do ingl\u00eas, show, marketing, estresse. Do franc\u00eas, bal\u00e9, garagem, champanhe. E  detalhe, que figura na can\u00e7\u00e3o de Roberto Carlos.  <\/p>\n<p>Muitos n\u00e3o gostam de estrangeirismos. Preferem voc\u00e1culos vindos do latim ou  do tupi-guarani. Detalhe entra na ca\u00e7ada. Em vez da francesinha, os intolerantes  ficam com <i>pormenor<\/i>, que vem de <i>por menor<\/i>. Ambas t\u00eam o mesmo  significado. S\u00e3o min\u00facias.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detalhe \u00e9 galicismo? (A. Toledo Ferreira) Galicismo \u00e9 palavra, constru\u00e7\u00e3o ou locu\u00e7\u00e3o da l\u00edngua francesa tomada de empr\u00e9stimo por outra l\u00edngua. O portugu\u00eas n\u00e3o faz cerim\u00f4nia. Enriquece o l\u00e9xico com contribui\u00e7\u00f5es de diferentes nacionalidades. Do \u00e1rabe, incorporou \u00e1lcool, algod\u00e3o, bazar. Do alem\u00e3o, campe\u00e3o, blitz. Do italiano, fiasco, pizza, carnaval. Do ingl\u00eas, show, marketing, estresse. Do franc\u00eas, bal\u00e9, garagem, champanhe. E detalhe, que figura na can\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-5997","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5997"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5997\/revisions"}],"predecessor-version":[{"id":11383,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5997\/revisions\/11383"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}