{"id":588,"date":"2015-08-18T00:00:00","date_gmt":"2015-08-18T00:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/08\/18\/leitor_pergunta-36\/"},"modified":"2015-11-12T19:39:48","modified_gmt":"2015-11-12T21:39:48","slug":"leitor_pergunta-36","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-36\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"\n<p>  Nos t\u00edtulos de mat\u00e9ria de jornal, procuramos,  sempre que poss\u00edvel, empregar o presente. Podemos proceder assim mesmo que um  evento ainda n\u00e3o tenha ocorrido? Ou, nesse caso, s\u00f3 podemos usar o  futuro? (Gabriela Lacerda) <b> <\/p>\n<p><\/b>  <\/p>\n<p>O presente, Gabi, \u00e9 tempo pra l\u00e1 de vers\u00e1til.  Adapta-se ao presente, ao passado e ao futuro: <i> <\/p>\n<p><\/i><i>Estudo ingl\u00eas todos os dias. Viajo no fim  do ano. Em 1500, Pedro \u00c1lvares Cabral sai de Bel\u00e9m e chega a este pa\u00eds que, de  t\u00e3o grande, parece continente.<\/i> &nbsp; <\/p>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nos t\u00edtulos de mat\u00e9ria de jornal, procuramos, sempre que poss\u00edvel, empregar o presente. Podemos proceder assim mesmo que um evento ainda n\u00e3o tenha ocorrido? Ou, nesse caso, s\u00f3 podemos usar o futuro? (Gabriela Lacerda) O presente, Gabi, \u00e9 tempo pra l\u00e1 de vers\u00e1til. Adapta-se ao presente, ao passado e ao futuro: Estudo ingl\u00eas todos os dias. Viajo no fim do ano. Em 1500, Pedro \u00c1lvares [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-588","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=588"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/588\/revisions"}],"predecessor-version":[{"id":864,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/588\/revisions\/864"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}