{"id":586,"date":"2015-08-17T13:30:00","date_gmt":"2015-08-17T13:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/08\/17\/metralhadora_contra_a_lingua_1\/"},"modified":"2015-10-23T16:51:47","modified_gmt":"2015-10-23T18:51:47","slug":"metralhadora_contra_a_lingua_1","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/metralhadora_contra_a_lingua_1\/","title":{"rendered":"Metralhadora contra a l\u00edngua 1"},"content":{"rendered":"\n<p> Pode? Militar aposentado andava com submetralhadora  pra cima e pra baixo pelas ruas de Porto Alegre. Circulava armado com a  naturalidade de quem respira ou bebe \u00e1gua pra matar a sede. Num descuido do  valent\u00e3o, a pol\u00edcia o prendeu. E, claro, foi \u00e0 casa dele pra descobrir o que  havia por l\u00e1. Ops! O homem tinha armas pra dar, vender e emprestar.   <\/p>\n<p> Jornais, r\u00e1dios, tev\u00eas e internet noticiaram o fato.  Alguns trope\u00e7aram na l\u00edngua. Duas v\u00edtimas gritaram por socorro. Uma delas: a  grafia. A outra: a economia verbal. Uns escreveram sub-metralhadora. O h\u00edfen  esperneou. Outros, arsenal de armas. Bobearam. Abusaram do espa\u00e7o e da paci\u00eancia  do leitor. Sabe por qu\u00ea?  <\/p>\n<p> <b>O sub<\/b>  <\/p>\n<p> Sub pede h\u00edfen? N\u00e3o pede? Pra acertar sempre,  lembre-se das tr\u00eas regras de ouro no emprego do tracinho depois de  prefixos:  <\/p>\n<p> 1. O h \u00e9 majestoso. N\u00e3o se mistura: <i>anti-her\u00f3i,  super-homem, sub-hep\u00e1tico<\/i>. 2. Letras diferentes se atraem. Com elas \u00e9 tudo  colado: <i>autoescola, microrregi\u00e3o, subsolo.<\/i> 3. Letras iguais se rejeitam. Fica uma l\u00e1 e outra c\u00e1:  <i>micro-ondas, contra-ataque, sub-bloco.<\/i>  <\/p>\n<p> <b>Sem bobeira<\/b>  <\/p>\n<p> Simples assim. Mas o h\u00edfen \u00e9 castigo de Deus. As  regras t\u00eam exce\u00e7\u00f5es. Uma se refere ao prefixo <i>sub<\/i>. Ele joga no time dos  encontros consonantais. Ao se encontrar com o <i>r<\/i>, ocorre casamento  autom\u00e1tico. As duas letras passam a se pronunciar juntas. \u00c9 o caso de a-bra-\u00e7o,  co-bre e o-bri-ga-\u00e7\u00e3o. Pra separar a duplinha, s\u00f3 h\u00e1 uma sa\u00edda \u2014 convocar o  tracinho. Assim: <i>sub-ra\u00e7a, sub-reitor, sub-repasse,  sub-regi\u00e3o.<\/i>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pode? Militar aposentado andava com submetralhadora pra cima e pra baixo pelas ruas de Porto Alegre. Circulava armado com a naturalidade de quem respira ou bebe \u00e1gua pra matar a sede. Num descuido do valent\u00e3o, a pol\u00edcia o prendeu. E, claro, foi \u00e0 casa dele pra descobrir o que havia por l\u00e1. Ops! O homem tinha armas pra dar, vender e emprestar. Jornais, r\u00e1dios, tev\u00eas [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-586","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=586"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/586\/revisions"}],"predecessor-version":[{"id":866,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/586\/revisions\/866"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}