{"id":577,"date":"2015-08-12T10:35:00","date_gmt":"2015-08-12T10:35:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/08\/12\/de_passado_e_futuro\/"},"modified":"2015-10-23T16:51:54","modified_gmt":"2015-10-23T18:51:54","slug":"de_passado_e_futuro","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/de_passado_e_futuro\/","title":{"rendered":"De passado e futuro"},"content":{"rendered":"\n<p>Cilene Maria \u00e9 velha redatora. Escreve relat\u00f3rios, cartas, e-mails,  artigos. Tem conta no Twitter e seguidores \u00e0 be\u00e7a no Facebook. Mas, apesar da  experi\u00eancia, acontece com ela o que acontece a muitos de n\u00f3s. Pintam d\u00favidas.  Uma das mais teimosas \u00e9 o emprego da preposi\u00e7\u00e3o <i>a<\/i> e do verbo <i>h\u00e1<\/i>.  Sempre que precisa falar de contagem de tempo, para, respira, pensa e&#8230;  consulta gram\u00e1ticas ou manuais.  <\/p>\n<p> \u201cH\u00e1  alguma superdica que possa me tirar da enrascada rapidinho?\u201d, pergunta ela.  Claro que sim. Guarde isto: <i>h\u00e1<\/i> indica passado; <i>a <\/i>exprime futuro. O passado, convenhamos, pesa.  Da\u00ed por que tem carga maior \u2014 duas letras e acento. O futuro se caracteriza pela  leveza. Basta um azinho pra indic\u00e1-lo. Compare: <i>Cheguei h\u00e1 pouco. Daqui a  pouco, chegarei. Partiu h\u00e1 cerca de 20 minutos. Partir\u00e1 daqui a 20 minutos. A  cerca de 20 minutos da partida, despediu-se dos amigos.<\/i>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cilene Maria \u00e9 velha redatora. Escreve relat\u00f3rios, cartas, e-mails, artigos. Tem conta no Twitter e seguidores \u00e0 be\u00e7a no Facebook. Mas, apesar da experi\u00eancia, acontece com ela o que acontece a muitos de n\u00f3s. Pintam d\u00favidas. Uma das mais teimosas \u00e9 o emprego da preposi\u00e7\u00e3o a e do verbo h\u00e1. Sempre que precisa falar de contagem de tempo, para, respira, pensa e&#8230; consulta gram\u00e1ticas ou [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-577","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=577"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/577\/revisions"}],"predecessor-version":[{"id":875,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/577\/revisions\/875"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}