{"id":576,"date":"2015-08-12T10:35:00","date_gmt":"2015-08-12T10:35:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/08\/12\/be-a-ba\/"},"modified":"2015-10-23T16:51:55","modified_gmt":"2015-10-23T18:51:55","slug":"be-a-ba","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/be-a-ba\/","title":{"rendered":"B\u00ea-\u00e1-b\u00e1"},"content":{"rendered":"\n<p> \u201cN\u00e3o \u00e9 que eu queira o b\u00ea-a-b\u00e1\u201d, escreveu a GloboNews  na telinha. Bobeou. O nome do conjunto de letras do abeced\u00e1rio n\u00e3o goza de  privil\u00e9gios. Precisa respeitar o vocabul\u00e1rio ortogr\u00e1fico. T\u00f4nica, a  primeirona do alfabeto se escreve com acento. Que tal fazer as pazes com a  grafia? H\u00e1 duas sa\u00eddas. Uma: b\u00ea-\u00e1-b\u00e1. A outra:  beab\u00e1.<b> <\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cN\u00e3o \u00e9 que eu queira o b\u00ea-a-b\u00e1\u201d, escreveu a GloboNews na telinha. Bobeou. O nome do conjunto de letras do abeced\u00e1rio n\u00e3o goza de privil\u00e9gios. Precisa respeitar o vocabul\u00e1rio ortogr\u00e1fico. T\u00f4nica, a primeirona do alfabeto se escreve com acento. Que tal fazer as pazes com a grafia? H\u00e1 duas sa\u00eddas. Uma: b\u00ea-\u00e1-b\u00e1. A outra: beab\u00e1.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-576","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=576"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/576\/revisions"}],"predecessor-version":[{"id":876,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/576\/revisions\/876"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}