{"id":5711,"date":"2011-02-06T00:10:00","date_gmt":"2011-02-06T02:10:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_nova_ortografia\/"},"modified":"2011-02-06T00:10:00","modified_gmt":"2011-02-06T02:10:00","slug":"a_nova_ortografia","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_nova_ortografia\/","title":{"rendered":"A nova ortografia"},"content":{"rendered":"<p>&nbsp;  <BR><I><\/I>&nbsp; <I>Muitas palavras mudaram, mas outras n\u00e3o&#8230;.Em casos como <\/I>AUTOESTIMA, o h\u00edfen caiu. A sua \u00e9 que n\u00e3o pode cair&#8230; jamais! <BR> &nbsp; Em algumas palavras, o acento desapareceu, como em FEIURA. Ali\u00e1s, poderia desaparecer a palavra toda. <BR> &nbsp; O acento tamb\u00e9m caiu em IDEIA, s\u00f3 que dela a gente precisa. E muito. <BR> &nbsp; O trema sumiu em todas as palavras, como em INCONSEQU\u00caNCIA, que tamb\u00e9m poderia sumir do mapa. Assim, a gente ia viver com mais TRANQUILIDADE. <BR> &nbsp; Mas nem tudo vai mudar. ABRA\u00c7O continua igual. E quanto mais apertado, melhor. <BR> &nbsp; AMIZADE ainda \u00e9 com &#8220;z&#8221;, como feliz, beleza, dez, &#8230; Voc\u00ea \u00e9 \u201cdez\u201d! <BR> &nbsp; Express\u00f5es como &#8220;EU TE AMO&#8221; continuam precisando de ponto. Se for de exclama\u00e7\u00e3o, \u00e9 PAIX\u00c3O, que continua com &#8220;x&#8221;, como abacaxi, que, gostando ou n\u00e3o, a gente vai ter alguns para descascar. <BR> &nbsp; SOLIT\u00c1RIO ainda tem acento, como SOLID\u00c1RIO, que s\u00f3 muda uma letra, mas faz uma enorme diferen\u00e7a. <BR> &nbsp; CONSCI\u00caNCIA ainda \u00e9 com &#8220;sc&#8221; e vamos precisar de muita para deixar o planeta mais sustent\u00e1vel e assim tocar a vida pra frente. Sempre! <BR> &nbsp; E, por falar em VIDA, bom, essa muda o tempo todo, e \u00e9 por isso que emociona tanto. <BR> &nbsp; Um &nbsp;excelente fim de&nbsp;semana!&nbsp; &nbsp; &nbsp; (Colabora\u00e7\u00e3o de Paulo Jos\u00e9 Cunha.)  <BR> <DIV>&nbsp;<\/DIV> <DIV>&nbsp;<\/DIV> <DIV>&nbsp;<\/DIV><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Muitas palavras mudaram, mas outras n\u00e3o&#8230;.Em casos como AUTOESTIMA, o h\u00edfen caiu. A sua \u00e9 que n\u00e3o pode cair&#8230; jamais! &nbsp; Em algumas palavras, o acento desapareceu, como em FEIURA. Ali\u00e1s, poderia desaparecer a palavra toda. &nbsp; O acento tamb\u00e9m caiu em IDEIA, s\u00f3 que dela a gente precisa. E muito. &nbsp; O trema sumiu em todas as palavras, como em INCONSEQU\u00caNCIA, que [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5711","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5711"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5711\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}