{"id":5674,"date":"2011-11-04T00:00:00","date_gmt":"2011-11-04T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_calo_do_ordinal\/"},"modified":"2011-11-04T00:00:00","modified_gmt":"2011-11-04T02:00:00","slug":"o_calo_do_ordinal","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_calo_do_ordinal\/","title":{"rendered":"O calo do ordinal"},"content":{"rendered":"<div>\n<p><b>  <\/p>\n<p><\/b> Duas not\u00edcias chamaram a aten\u00e7\u00e3o nesta semana. Ambas se  referem a n\u00fameros. A primeira: o Brasil aparece em 84\u00ba lugar no ranking do  \u00cdndice de Desenvolvimento Humano (IDH) da ONU. A outra: Dilma figura na 22\u00aa  posi\u00e7\u00e3o na lista das pessoas mais poderosas do mundo. Uns dias antes, nova cifra  ocupou as manchetes. A Terra recebeu novo morador. \u00c9 o 7.000.000.000\u00ba  habitante.   <\/p>\n<p>A divulga\u00e7\u00e3o trouxe desafios. Respostas se impuseram. A mais  urgente bateu \u00e0 porta de rep\u00f3rteres. Como dizer os ordinais? Os curtinhos s\u00e3o  moleza. A escola os ensina desde sempre. R\u00e1dios e tev\u00eas os repetem. N\u00f3s os  memorizamos. \u00c9 o caso de primeiro, segundo, quinto, d\u00e9cimo, d\u00e9cimo sexto,  vig\u00e9simo, trig\u00e9simo, quadrag\u00e9simo, quinquag\u00e9simo, sexag\u00e9simo, septuag\u00e9simo (ou  setuag\u00e9simo), octog\u00e9simo, nonag\u00e9simo, cent\u00e9simo.   <\/p>\n<p>A porca torce o rabo com os grand\u00f5es. Vale o exemplo de  7.000.000.000\u00ba. Como pronunci\u00e1-lo sem ferir ouvidos sens\u00edveis? Dica: os ordinais  se caracterizam pela monotonia.&nbsp;Com eles \u00e9 ordinal ou ordinal. O ordinal de 1  bilh\u00e3o \u00e9 bilion\u00e9simo. De 2 bilh\u00f5es, segundo bilion\u00e9simo; de 3 bilh\u00f5es, terceiro  bilion\u00e9simo; de 4 bilh\u00f5es, quarto bilion\u00e9simo; de 5 bilh\u00f5es, quinto bilion\u00e9simo;  de 6 bilh\u00f5es, s\u00e9timo bilion\u00e9simo. De 7 bilh\u00f5es? Claro, \u00e9 s\u00e9timo  bilion\u00e9simo.   <\/p>\n<p>E depois? O jeit\u00e3o se mant\u00e9m. Basta acrescentar ordinais e  ordinais \u2014 sempre ordinais: quinto milion\u00e9simo terceiro (5.000.003\u00ba), s\u00e9timo  bilion\u00e9simo primeiro (7.000.000.001\u00ba), quarto bilion\u00e9simo tricent\u00e9simo trig\u00e9simo  terceiro (4.000.000.333\u00ba).<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n<p>Seis e meia d\u00fazia<\/b>   <\/p>\n<p>Ufa! A l\u00edngua \u00e9 como a mulher de C\u00e9sar. N\u00e3o bastava \u00e0  primeira-dama do Imp\u00e9rio Romano ser honesta. Ela tinha de parecer honesta. \u00c0  l\u00edngua tamb\u00e9m n\u00e3o basta ser correta. Precisa parecer correta. Se o n\u00famero soa  estranho, apele para outra possibilidade. Diga o cardinal mesmo. Em vez do  comprid\u00edssimo <i>cent\u00e9simo d\u00e9cimo<\/i> <i>segundo<\/i> lugar, fique com  <i>classifica\u00e7\u00e3o n\u00ba 112.<\/i> <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Duas not\u00edcias chamaram a aten\u00e7\u00e3o nesta semana. Ambas se referem a n\u00fameros. A primeira: o Brasil aparece em 84\u00ba lugar no ranking do \u00cdndice de Desenvolvimento Humano (IDH) da ONU. A outra: Dilma figura na 22\u00aa posi\u00e7\u00e3o na lista das pessoas mais poderosas do mundo. Uns dias antes, nova cifra ocupou as manchetes. A Terra recebeu novo morador. \u00c9 o 7.000.000.000\u00ba habitante. A divulga\u00e7\u00e3o trouxe [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5674","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5674"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5674\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}