{"id":5669,"date":"2011-01-28T14:21:00","date_gmt":"2011-01-28T16:21:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/vocabulario\/"},"modified":"2011-01-28T14:21:00","modified_gmt":"2011-01-28T16:21:00","slug":"vocabulario","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/vocabulario\/","title":{"rendered":"Vocabul\u00e1rio"},"content":{"rendered":"<p><a style=\"font-weight: bold\" href=\"http:\/\/stat.correioweb.com.br\/00CW\/280111_vocabulario.pps\">Apresenta\u00e7\u00e3o <\/a>em formato .pdf  <\/p>\n<p>Tamanho do arquivo: 984 Kb  <\/p>\n<p>(Colabora\u00e7\u00e3o de Leda Watson)  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apresenta\u00e7\u00e3o em formato .pdf Tamanho do arquivo: 984 Kb (Colabora\u00e7\u00e3o de Leda Watson)<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5669","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5669"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5669\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}