{"id":5583,"date":"2011-01-16T00:00:00","date_gmt":"2011-01-16T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_sete_pecados_dos_cruzamentos\/"},"modified":"2015-11-12T19:32:08","modified_gmt":"2015-11-12T21:32:08","slug":"os_sete_pecados_dos_cruzamentos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_sete_pecados_dos_cruzamentos\/","title":{"rendered":"Os sete pecados dos cruzamentos"},"content":{"rendered":"<p>  <BR>&nbsp; &nbsp; Eram nove conhecidos. Mas os antigos preferiram o n\u00famero cabal\u00edstico. Os sete mares \u2014 o Adri\u00e1tico, o Ar\u00e1bico, o C\u00e1spio, o Mediterr\u00e2neo, o Negro, o Vermelho e o Golfo P\u00e9rsico \u2014 inundaram a literatura medieval. H\u00e1 quem diga que a express\u00e3o nasceu nas p\u00e1ginas das Mil e uma noites. O marinheiro Simbad, um dos personagens das aventuras contadas por Sherazade, precisava levar mercadorias a portos distantes. Para chegar l\u00e1, navegava por sete mares. Com o tempo, as duas palavras ampliaram o significado. &#8220;Navegar por sete mares&#8221; \u00e9 viajar muito, sonhar muito, entregar-se a aventuras nunca dantes sonhadas. <BR> &nbsp; A l\u00edngua convive com fa\u00e7anhas semelhantes. Trata-se dos cruzamentos. Sem entender o qu\u00ea ou o porqu\u00ea, criaturas atrevidas embarcam em del\u00edrios lingu\u00edsticos. Misturam alhos com bugalhos. Tomam peda\u00e7o de uma estrutura e o juntam a peda\u00e7o de outra. \u00c9 como cruzar elefante com gato. O resultado? Valha-nos, Deus! \u00c9 a receita do cruz-credo. Quer ver? Eis os sete pecados da combina\u00e7\u00e3o heterodoxa. <BR>&nbsp; <BR> <STRONG><\/STRONG>&nbsp; <STRONG>J\u00e1 x mais <BR><\/STRONG> &nbsp; Nas indica\u00e7\u00f5es temporais, existem dois bicudos. Um deles: j\u00e1. O outro: mais. Como diz o outro, eles n\u00e3o se beijam. Onde couber um, o outro n\u00e3o ter\u00e1 vez. Assim: Quando os bombeiros chegaram, as v\u00edtimas j\u00e1 n\u00e3o respiravam. J\u00e1 n\u00e3o h\u00e1 lei que iniba a invas\u00e3o dos morros. Quando entregou o projeto, n\u00e3o se preocupou mais. <BR> Olho vivo: Quando os bombeiros chegaram, as v\u00edtimas j\u00e1 n\u00e3o respiravam mais? J\u00e1 n\u00e3o h\u00e1 mais lei que iniba as invas\u00f5es? Quando entregou o projeto, j\u00e1 n\u00e3o se preocupou mais? X\u00f4\u00f4\u00f4\u00f4\u00f4\u00f4\u00f4\u00f4\u00f4\u00f4\u00f4! \u00c9 cruzamento. <BR>&nbsp; <BR> <STRONG>\u00c0 medida que x na medida em que <BR><\/STRONG> &nbsp; Parecido n\u00e3o \u00e9 igual. Mas confunde. Um dos n\u00f3s que enroscam os miolos s\u00e3o as locu\u00e7\u00f5es \u00e0 medida que e na medida em que. Trio e quarteto t\u00eam significados pr\u00f3prios. Com personalidade forte, detestam trapalhadas: <BR> &nbsp; \u00c0 medida que = \u00e0 propor\u00e7\u00e3o que: \u00c0 medida que exercito a leitura, leio melhor. \u00c0 medida que conhecia o amigo, encantava-se com as qualidades que demonstrava. Aumentava as risadas \u00e0 medida que ouvia as loucuras do viajante. <BR> &nbsp; Na medida em que = porque, tendo em vista: A trag\u00e9dia das chuvas se repete na medida em que n\u00e3o se tomam medidas corretivas e preventivas. A mortalidade infantil cai no Brasil na medida em que se deu mais aten\u00e7\u00e3o ao pr\u00e9-natal. <BR> &nbsp; Cuidado: na medida que? \u00c0 medida em que? Ops! \u00c9 cruzamento. X\u00f4! <BR>&nbsp; <BR> &nbsp; <STRONG>De \u2026 a <BR><\/STRONG> &nbsp; Na l\u00edngua h\u00e1 casaizinhos. Eles t\u00eam uma marca. S\u00e3o pra l\u00e1 de leais. A estrutura dos dois pares \u00e9 a mesma. \u00c9 o caso de de \u2026 a. De \u00e9 preposi\u00e7\u00e3o pura. A vai atr\u00e1s. Com a duplinha, por isso, a crase n\u00e3o tem vez: Trabalho de segunda a sexta. Estudo de domingo a domingo. Viajamos de segunda a quinta. <BR>&nbsp; <BR> <STRONG>Das \u2026 \u00e0s <BR><\/STRONG> &nbsp; Eis outro casalzinho. Das se forma da preposi\u00e7\u00e3o de + o artigo a. \u00c0s, fiel parceiro, tamb\u00e9m exibe preposi\u00e7\u00e3o (a) + artigo. Da\u00ed a crase: Corro da Rua da Praia \u00e0 Rua dos Andradas. Estudo das 8h \u00e0s 18h. Meu expediente: de segunda a sexta das 14h \u00e0s 20h. <BR> &nbsp; De\u2026\u00e0? Das\u2026as? Nem pensar. \u00c9 cruzamento. <BR>&nbsp; <BR> &nbsp; <STRONG>Ainda x mais <BR><\/STRONG> &nbsp; A l\u00edngua abriga mais bicudos do que imagina nossa v\u00e3o filosofia. Al\u00e9m do j\u00e1 x mais, temos o ainda x mais. Um dispensa o outro: O programa ainda vai levar cinco meses. O programa vai levar mais cinco meses. <BR> &nbsp; Ops! O programa ainda vai levar mais cinco meses? Nem a pedido de Deus. O cruzamento leva o autor a arder nas chamas do inferno. Eternamente. <BR>&nbsp; <BR> <STRONG><\/STRONG>&nbsp; <STRONG>Ainda x continua <BR><\/STRONG> &nbsp; Viu? O ainda indica continuidade. O continua tamb\u00e9m. Misturar os dois d\u00e1 briga. Fique com um deles: Apesar do despreparo f\u00edsico, Ronaldo continua \u00eddolo dos brasileiros.  <BR> &nbsp; Uiiiiiiiiiiiiiiiiiiiiiiiiiiii! Ronaldo ainda continua \u00eddolo dos brasileiros? Virgem Maria, protegei-nos. Livrai-nos da ira divina. <BR>&nbsp; <BR> <STRONG>A partir x come\u00e7ar <BR><\/STRONG> &nbsp; Aten\u00e7\u00e3o, marinheiros de poucas viagens. A partir significa a come\u00e7ar. Usar os dois d\u00e1 confus\u00e3o. Sem pregui\u00e7a, escolha um ou outro: A partir de domingo, o metr\u00f4 ter\u00e1 novo hor\u00e1rio. O novo hor\u00e1rio do metr\u00f4 come\u00e7a domingo. <BR> &nbsp; A partir de domingo o metr\u00f4 come\u00e7a a circular em novo hor\u00e1rio? Que desperd\u00edcio! Deus castiga.&nbsp; <BR>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Eram nove conhecidos. Mas os antigos preferiram o n\u00famero cabal\u00edstico. Os sete mares \u2014 o Adri\u00e1tico, o Ar\u00e1bico, o C\u00e1spio, o Mediterr\u00e2neo, o Negro, o Vermelho e o Golfo P\u00e9rsico \u2014 inundaram a literatura medieval. H\u00e1 quem diga que a express\u00e3o nasceu nas p\u00e1ginas das Mil e uma noites. O marinheiro Simbad, um dos personagens das aventuras contadas por Sherazade, precisava levar mercadorias [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,61],"tags":[],"class_list":["post-5583","post","type-post","status-publish","format-standard","hentry","category-geral","category-pecados-da-lingua"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5583"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5583\/revisions"}],"predecessor-version":[{"id":11139,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5583\/revisions\/11139"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}