{"id":5580,"date":"2011-01-15T08:00:00","date_gmt":"2011-01-15T10:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-92\/"},"modified":"2015-11-13T10:23:24","modified_gmt":"2015-11-13T12:23:24","slug":"leitor_pergunta-92","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-92\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"<p>  <BR>&nbsp; <STRONG>Estou fazendo um cart\u00e3o de agradecimento e gostaria de saber qual \u00e9 o certo: obrigado pela presen\u00e7a ou obrigada pela presen\u00e7a.<\/STRONG> (Dionne Lago Gon\u00e7alves) &nbsp; Ele diz obrigado. Ela, obrigada. Eta gente educada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Estou fazendo um cart\u00e3o de agradecimento e gostaria de saber qual \u00e9 o certo: obrigado pela presen\u00e7a ou obrigada pela presen\u00e7a. (Dionne Lago Gon\u00e7alves) &nbsp; Ele diz obrigado. Ela, obrigada. Eta gente educada.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-5580","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5580"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5580\/revisions"}],"predecessor-version":[{"id":11399,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5580\/revisions\/11399"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}