{"id":5526,"date":"2011-01-10T17:30:00","date_gmt":"2011-01-10T19:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-634\/"},"modified":"2015-11-12T16:40:55","modified_gmt":"2015-11-12T18:40:55","slug":"erramos-634","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-634\/","title":{"rendered":"Erramos"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Qual \u00e9 o melhor filme baseado em fatos reais?&#8221;,  perguntamos no Roteiro. Baita pleonasmo, n\u00e3o? Todo fato \u00e9 real. Da\u00ed por  que os ju\u00edzes pedem \u00e0s testemunhas &#8220;que se atenham aos fatos&#8221;. Melhor: Qual \u00e9 o  melhor filme baseado em hist\u00f3rias reais?<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Qual \u00e9 o melhor filme baseado em fatos reais?&#8221;, perguntamos no Roteiro. Baita pleonasmo, n\u00e3o? Todo fato \u00e9 real. Da\u00ed por que os ju\u00edzes pedem \u00e0s testemunhas &#8220;que se atenham aos fatos&#8221;. Melhor: Qual \u00e9 o melhor filme baseado em hist\u00f3rias reais?<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-5526","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5526"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5526\/revisions"}],"predecessor-version":[{"id":10330,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5526\/revisions\/10330"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}