{"id":5521,"date":"2011-01-09T00:05:00","date_gmt":"2011-01-09T02:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_sete_pecados_do_estilo\/"},"modified":"2015-11-12T19:32:10","modified_gmt":"2015-11-12T21:32:10","slug":"os_sete_pecados_do_estilo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_sete_pecados_do_estilo\/","title":{"rendered":"Os sete pecados do estilo"},"content":{"rendered":"<p>&nbsp; &nbsp; Maravilha tem sin\u00f4nimos. Um deles: fasc\u00ednio. Outro: perfei\u00e7\u00e3o. Muitos outros: admira\u00e7\u00e3o, deslumbramento, \u00eaxtase, primor, fen\u00f4meno, milagre. O mundo tem maravilhas. H\u00e1 as antigas, as medievais e as modernas. As mais vetustas ganharam notoriedade um s\u00e9culo e meio antes de Cristo. L\u00e1 se v\u00e3o 2.150 anos.  &nbsp; Os gregos, fascinados pela majestade de monumentos e esculturas feitos pelo homem, enumeraram sete: a Pir\u00e2mide de Qu\u00e9ops, os jardins suspensos da Babil\u00f4nia, A est\u00e1tua de Zeus em Ol\u00edmpia, o templo de \u00c1rtemis em \u00c9feso, o Mausol\u00e9u de Halicarnasso, o Colosso de Rodes e o Farol de Alexandria. <BR> &nbsp; Escritores tamb\u00e9m produziram obras que encantam gera\u00e7\u00f5es sem discrimina\u00e7\u00e3o de tempo, sexo ou idade. Os que vieram antes abriram caminho para os que vieram depois. E para os que vir\u00e3o. Todos t\u00eam uma marca. Sintonizam-se com a \u00e9poca em que vivem. A atual se caracteriza pela vaidade. Pneuzinhos nas costas? Est\u00f4mago exibido? Barriga nutrida? Coxas atrevidas? Vem, Pitanguy. A l\u00edngua tamb\u00e9m adora ser enxutinha. Quer tudo no lugar. Gordurinhas aqui e ali? X\u00f4! O cirurgi\u00e3o pl\u00e1stico manda as adiposidades bater em retirada. Quais? <BR> &nbsp; <STRONG>Um, uma <BR><\/STRONG> &nbsp; Voc\u00ea tem um jornal \u00e0 m\u00e3o? Escolha uma mat\u00e9ria. Leia-a. Depois, risque os artigos indefinidos. Volte a ler o texto. Reparou? O um e o uma n\u00e3o fazem falta. Ao contr\u00e1rio. Tornam o substantivo vago, impreciso, moleng\u00e3o. Em 99% dos casos, \u00e9 gordura pura. X\u00f4! Sem ele, o texto agradece. O leitor tamb\u00e9m: Dilma mereceu (uma) recep\u00e7\u00e3o calorosa. O Brasil tem (uma) nova presidente. H\u00e1 (umas) grandes expectativas em rela\u00e7\u00e3o ao novo governo.  <BR> &nbsp; <STRONG>Seu, sua <BR><\/STRONG> &nbsp; &#8220;Livro-me dos voc\u00e1bulos que est\u00e3o na frase s\u00f3 para enfeitar ou atrapalhar&#8221;, repetia George Simenon. O autor de romances policiais com certeza pensava nos possessivos seu, sua. \u00c0s vezes, eles tornam o enunciado amb\u00edguo; outras, sobram. Veja: No (seu) pronunciamento de posse, o governador fez promessas. Antes de sair, olhou para o (seu) rosto e as (suas) m\u00e3os. Ao chegar, tirou os (seus) \u00f3culos.  <BR> &nbsp; <STRONG>Aquele, aquela, aquilo<\/STRONG> <BR> &nbsp; &#8220;O que \u00e9 isso, companheiros?&#8221; Por alguma raz\u00e3o que nem Deus explica, os demonstrativos aquele, aquela, aquilo usurpam o lugar dos pequeninos o, a. Em vez dos discretos monoss\u00edlabos, a turma empanturra a frase com os pesad\u00edssimos triss\u00edlabos. Pau neles! Veja: Aqueles que nunca pecaram atirem a primeira pedra. (Os que nunca pecaram atirem a primeira pedra. Quem nunca pecou atire a primeira pedra.) Aquilo que \u00e9 escrito sem esfor\u00e7o \u00e9 lido sem prazer. (O que \u00e9 escrito sem esfor\u00e7o \u00e9 lido sem prazer.)  <BR> &nbsp; <STRONG>Locu\u00e7\u00e3o adjetiva <BR><\/STRONG> &nbsp; Lembre-se: menos \u00e9 mais. Menos palavras \u00e9 mais concis\u00e3o. Material de guerra \u00e9 material b\u00e9lico. Pessoa sem discri\u00e7\u00e3o \u00e9 pessoa indiscreta. Crian\u00e7a sem educa\u00e7\u00e3o \u00e9 crian\u00e7a mal-educada. L\u00edquido sem cheiro \u00e9 inodoro.  <BR> &nbsp; <STRONG>Ora\u00e7\u00f5es adjetivas <BR><\/STRONG> &nbsp; Pessoa que se alimenta de verduras e legumes (pessoa vegetariana). Homem que planta caf\u00e9 (cafeicultor). Crian\u00e7a que n\u00e3o sabe ler nem escrever (crian\u00e7a analfabeta). Bras\u00edlia, que \u00e9 a capital do Brasil, tem 2,5 milh\u00f5es de habitantes. (Bras\u00edlia, a capital do Brasil, tem 2,5 milh\u00f5es e habitantes.)  <BR> &nbsp; <STRONG>Formas longas<\/STRONG> <BR> &nbsp; P\u00f4r as ideias em ordem \u00e9 ordenar as ideias. P\u00f4r moeda em circula\u00e7\u00e3o \u00e9 emitir moeda. Fazer uma viagem \u00e9 viajar. Ver a beleza do quadro \u00e9 admirar o quadro.  <BR>Mais: Este trabalho visa analisar as causas da viol\u00eancia dom\u00e9stica. (Este trabalho apontar\u00e1 as causas da viol\u00eancia dom\u00e9stica.) Esta tese busca discutir o preconceito racial nas escolas. (Este trabalho analisa o preconceito racial nas escolas.) O cantor pode apresentar nova can\u00e7\u00e3o durante o espet\u00e1culo. (O cantor apresentar\u00e1 nova can\u00e7\u00e3o durante o espet\u00e1culo.) <BR><STRONG><\/STRONG> <STRONG><\/STRONG>&nbsp; <STRONG>Bl\u00e1-bl\u00e1-bl\u00e1 <BR><\/STRONG> &nbsp; O desnecess\u00e1rio sobra. Se sobra, n\u00e3o faz falta. Se n\u00e3o faz falta, x\u00f4! Curso em n\u00edvel de p\u00f3s gradua\u00e7\u00e3o? \u00c9 curso de p\u00f3s-gradua\u00e7\u00e3o. Decis\u00e3o tomada no \u00e2mbito do partido? \u00c9 decis\u00e3o do partido. Doen\u00e7a de natureza sexual? \u00c9 doen\u00e7a sexual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Maravilha tem sin\u00f4nimos. Um deles: fasc\u00ednio. Outro: perfei\u00e7\u00e3o. Muitos outros: admira\u00e7\u00e3o, deslumbramento, \u00eaxtase, primor, fen\u00f4meno, milagre. O mundo tem maravilhas. H\u00e1 as antigas, as medievais e as modernas. As mais vetustas ganharam notoriedade um s\u00e9culo e meio antes de Cristo. L\u00e1 se v\u00e3o 2.150 anos. &nbsp; Os gregos, fascinados pela majestade de monumentos e esculturas feitos pelo homem, enumeraram sete: a Pir\u00e2mide de [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,61],"tags":[],"class_list":["post-5521","post","type-post","status-publish","format-standard","hentry","category-geral","category-pecados-da-lingua"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5521"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5521\/revisions"}],"predecessor-version":[{"id":11142,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5521\/revisions\/11142"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}