{"id":5369,"date":"2010-09-22T08:00:00","date_gmt":"2010-09-22T11:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/pra_la_de_educado\/"},"modified":"2010-09-22T08:00:00","modified_gmt":"2010-09-22T11:00:00","slug":"pra_la_de_educado","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/pra_la_de_educado\/","title":{"rendered":"Pra l\u00e1 de educado"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p><\/b>  <\/p>\n<p>&#8220;Obrigado&#8221;, diz ele. &#8220;Obrigada&#8221;, diz ela. &#8220;Por nada&#8221;,  respondem os dois. Ambos agradecem. T\u00e3o civilizado verbo exige cuidado na  reg\u00eancia. Agradecemos <strong>a<\/strong> algu\u00e9m <strong>por<\/strong> alguma  coisa: Agrade\u00e7a <strong>a<\/strong> Deus. Agradecemos <strong>a<\/strong>os  amigos. Quero agradecer <strong>a<\/strong>o diretor pela  promo\u00e7\u00e3o.  <\/p>\n<p>Aten\u00e7\u00e3o, gente educada. Na substitui\u00e7\u00e3o do algu\u00e9m  pelo pronome, abra os dois olhos. D\u00ea a vez ao <strong>lhe<\/strong>:  Agrade\u00e7o-lhes pela colabora\u00e7\u00e3o. Quero lhe agradecer pela lembran\u00e7a. Quem lhe  agradece primeiro?<b> &nbsp;<\/b> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Obrigado&#8221;, diz ele. &#8220;Obrigada&#8221;, diz ela. &#8220;Por nada&#8221;, respondem os dois. Ambos agradecem. T\u00e3o civilizado verbo exige cuidado na reg\u00eancia. Agradecemos a algu\u00e9m por alguma coisa: Agrade\u00e7a a Deus. Agradecemos aos amigos. Quero agradecer ao diretor pela promo\u00e7\u00e3o. Aten\u00e7\u00e3o, gente educada. Na substitui\u00e7\u00e3o do algu\u00e9m pelo pronome, abra os dois olhos. D\u00ea a vez ao lhe: Agrade\u00e7o-lhes pela colabora\u00e7\u00e3o. Quero lhe agradecer pela lembran\u00e7a. Quem [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5369","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5369"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5369\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}