{"id":5325,"date":"2010-09-15T14:00:00","date_gmt":"2010-09-15T17:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/palanque_eletronico_15\/"},"modified":"2010-09-15T14:00:00","modified_gmt":"2010-09-15T17:00:00","slug":"palanque_eletronico_15","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/palanque_eletronico_15\/","title":{"rendered":"Palanque eletr\u00f4nico 15"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Falar sem dizer  <\/p>\n<p>Dad Squarisi    <\/p>\n<p>Somos privilegiados. Temos quatro candidatos que s\u00f3 querem o bem da cidade.  Com o discurso na ponta da l\u00edngua, escorregam bem. D\u00e3o a impress\u00e3o de que  respondem, mas falam sem dizer. Prova? Brand\u00e3o apela pra tautologia. Quer ganhar  ganhando. Tamb\u00e9m faz m\u00e1gicas. Diz que sempre foi oposi\u00e7\u00e3o ao ex-governo Joaquim  Roriz. Ops! Ser oposi\u00e7\u00e3o ao ex-governo? \u00c9 bater no nada. Sem ligar, ele rima:  &#8220;Dia tr\u00eas, vote 43&#8221;.    <\/p>\n<p>&#8220;Sou o melhor&#8221;, diz Roriz. Confiante na experi\u00eancia, abusa de pleonasmos.  Esbanja &#8220;h\u00e1 anos atr\u00e1s&#8221;. Agnelo n\u00e3o fala em meia gravidez. Fala em &#8220;pouco  honesto&#8221;. Toninho p\u00f5e os pontos nos is: &#8220;Considero que chamar a pessoa de pouco  honesta \u00e9 cham\u00e1-la de desonesta&#8221;. Criativo, &#8220;quer as contas publicizadas&#8221;. Em  grupo heterog\u00eaneo, sobressai um ponto comum. Qual? &#8220;Vote em mim.<a name=\"Save1\"><\/a>&#8220;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Falar sem dizer Dad Squarisi Somos privilegiados. Temos quatro candidatos que s\u00f3 querem o bem da cidade. Com o discurso na ponta da l\u00edngua, escorregam bem. D\u00e3o a impress\u00e3o de que respondem, mas falam sem dizer. Prova? Brand\u00e3o apela pra tautologia. Quer ganhar ganhando. Tamb\u00e9m faz m\u00e1gicas. Diz que sempre foi oposi\u00e7\u00e3o ao ex-governo Joaquim Roriz. Ops! Ser oposi\u00e7\u00e3o ao ex-governo? \u00c9 bater no nada. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5325","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5325"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5325\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}