{"id":5320,"date":"2010-09-14T10:30:00","date_gmt":"2010-09-14T13:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitores_perguntam-5\/"},"modified":"2015-11-13T10:25:28","modified_gmt":"2015-11-13T12:25:28","slug":"leitores_perguntam-5","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitores_perguntam-5\/","title":{"rendered":"Leitores perguntam"},"content":{"rendered":"<p><b> <\/p>\n<p><\/b>     <\/p>\n<p>Estou preocupada. Meu chefe insiste em dizer (e  escrever) &#8220;f\u00e9rias longa&#8221; e &#8220;meu \u00f3culos&#8221;. A fala dele me soa mal. A leitura me  arrepia.&nbsp;Sempre soube&nbsp;que f\u00e9rias  e \u00f3culos s\u00e3o substantivos que se usam sempre no plural. Os adjuntos v\u00e3o  atr\u00e1s. Estou certa? (Carmem Goulart) <\/p>\n<p>    <strong> <\/p>\n<p><\/strong>    Cert\u00edssima. <i>F\u00e9rias<\/i> e <i>\u00f3culos<\/i> se  escrevem sempre no plural. Artigos, pronomes, adjetivos e verbos concordam com  eles. V\u00e3o para o plural: <i>As f\u00e9rias de julho foram boas. Onde est\u00e3o meus  \u00f3culos escuros? <\/i>     <\/p>\n<p>***     <\/p>\n<p>Os comentaristas pol\u00edticos&nbsp; me  confundem. Ora ou\u00e7o-os dizer &#8220;candidato  melhor classificado&#8221;. Ora, &#8220;candidato mais bem classificado&#8221;. Quem est\u00e1  certo? Quando usar mais bem e mais  mal? (L\u00edgia Alencar) <\/p>\n<p>   <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><\/b>  <\/p>\n<p>Mais bem e mais mal se  escrevem em duas situa\u00e7\u00f5es:      <\/p>\n<p>1. antes de partic\u00edpio: trabalho mais bem  escrito, casa mais bem decorada, candidato  mais bem classificado, candidato mais mal  classificado.     <\/p>\n<p>2. em compara\u00e7\u00f5es como estas: Trabalha mais bem  do que mal. Fala mais mal do que bem.      <\/p>\n<p>No mais, s\u00f3 o melhor tem vez. Abra-lhe alas  e estenda-lhe&nbsp;o tapete  vermelho.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estou preocupada. Meu chefe insiste em dizer (e escrever) &#8220;f\u00e9rias longa&#8221; e &#8220;meu \u00f3culos&#8221;. A fala dele me soa mal. A leitura me arrepia.&nbsp;Sempre soube&nbsp;que f\u00e9rias e \u00f3culos s\u00e3o substantivos que se usam sempre no plural. Os adjuntos v\u00e3o atr\u00e1s. Estou certa? (Carmem Goulart) Cert\u00edssima. F\u00e9rias e \u00f3culos se escrevem sempre no plural. Artigos, pronomes, adjetivos e verbos concordam com eles. V\u00e3o para o plural: [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-5320","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5320"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5320\/revisions"}],"predecessor-version":[{"id":11460,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5320\/revisions\/11460"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}