{"id":528,"date":"2015-07-17T14:00:00","date_gmt":"2015-07-17T14:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/07\/17\/jose_saramago_ensinou\/"},"modified":"2015-10-23T16:54:52","modified_gmt":"2015-10-23T18:54:52","slug":"jose_saramago_ensinou","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/jose_saramago_ensinou\/","title":{"rendered":"Jos\u00e9 Saramago ensinou"},"content":{"rendered":"\n<p>\u201cSinais de pontua\u00e7\u00e3o s\u00e3o como os de estrada. Se  tiv\u00e9ssemos menos deles, haveria por certo menos acidentes porque as pessoas  fariam tudo mais devagar e com maior aten\u00e7\u00e3o.\u201d  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSinais de pontua\u00e7\u00e3o s\u00e3o como os de estrada. Se tiv\u00e9ssemos menos deles, haveria por certo menos acidentes porque as pessoas fariam tudo mais devagar e com maior aten\u00e7\u00e3o.\u201d<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-528","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=528"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/528\/revisions"}],"predecessor-version":[{"id":926,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/528\/revisions\/926"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}