{"id":5054,"date":"2010-12-14T17:00:00","date_gmt":"2010-12-14T19:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/licao_do_corpo\/"},"modified":"2010-12-14T17:00:00","modified_gmt":"2010-12-14T19:00:00","slug":"licao_do_corpo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/licao_do_corpo\/","title":{"rendered":"Li\u00e7\u00e3o do corpo"},"content":{"rendered":"<div><i><\/i> <\/p>\n<p>O corpo ensina a li\u00e7\u00e3o \u00e0 l\u00edngua. Fun\u00e7\u00f5es iguais t\u00eam estruturas iguais. Temos  dois ouvidos. Eles desempenham o mesmo papel. Ouvem. Temos dois olhos. Um e  outro veem. Temos duas narinas. Ambas cheiram. Temos dois bra\u00e7os. A duplinha  abra\u00e7a. As duas pernas? Andam. Os 10 dedos? Seguram.  <\/p>\n<p>Boa aluna, a l\u00edngua vai atr\u00e1s. Se a ora\u00e7\u00e3o tem termos compostos, todos ter\u00e3o  a mesma cara. Se um for substantivo, os demais ser\u00e3o. Se adjetivo, idem. Se  ora\u00e7\u00e3o, tamb\u00e9m. Quer ver?<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p>Bons exemplos <\/b><b> <\/p>\n<p><\/b><b> <\/p>\n<p><\/b><b>Paulo, Lu\u00eds e Maria <\/b><i>assistiram ao show de Maria Bethania. (<\/i>A  ora\u00e7\u00e3o tem tr\u00eas sujeitos. Os tr\u00eas s\u00e3o substantivos \u2014 Paulo, Lu\u00eds,  Maria.)<b><i> <\/i><\/b><b><i> <\/p>\n<p><\/i><\/b><b><i> <\/p>\n<p><\/i><\/b><b><i>Ver e ouvir <\/i><\/b><i>\u00e9 o segredo do bom rep\u00f3rter. <\/i>(A ora\u00e7\u00e3o tem dois  sujeitos. Ambos verbos no infinitivo \u2014 ver e ouvir.) <i> <\/i><i> <\/p>\n<p><\/i><i> <\/p>\n<p><\/i><i>O presidente declarou <b>sua satisfa\u00e7\u00e3o<\/b> com a chegada dos chefes de  Estado a Bras\u00edlia e <b>a<\/b> <b>certeza<\/b> de que o Brasil far\u00e1 bons neg\u00f3cios.  <\/i>(O verbo <i>declarou<\/i> tem dois objetos. Os dois come\u00e7am com substantivo.  Um: a <i>satisfa\u00e7\u00e3o<\/i> com a chegada dos chefes de Estado a Bras\u00edlia. O outro:  a <i>certeza<\/i> de que o Brasil far\u00e1 bons neg\u00f3cios.)<i> <\/i><i> <\/p>\n<p><\/i><i> <\/p>\n<p><\/i><i>O presidente declarou que estava satisfeito com a chegada dos chefes de  Estado e que tem certeza da realiza\u00e7\u00e3o de bons neg\u00f3cios. <\/i>(O verbo  <i>declarou <\/i>tem dois objetos. Ambos s\u00e3o ora\u00e7\u00f5es. Uma: que estava satisfeito  com a chegada dos chefes de Estado a Bras\u00edlia. A outra: que tem certeza da  realiza\u00e7\u00e3o de bons neg\u00f3cios.)<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/b><b> <\/p>\n<p><\/b><b> <\/p>\n<p><\/b><b>Mau exemplo<\/b>  <\/p>\n<p>O presidente declarou satisfa\u00e7\u00e3o com a chegada dos chefes de Estado a  Bras\u00edlia e que o <i>Brasil far\u00e1 bons neg\u00f3cios.<\/i> (Viu? <i>Declarou <\/i>tem  dois objetos. O primeiro \u00e9 substantivo \u2014 <i>satisfa\u00e7\u00e3o<\/i>. O segundo, ora\u00e7\u00e3o \u2014  <i>que o Brasil far\u00e1 bons neg\u00f3cios<\/i>. \u00c9 o samba do paralelismo  doido.)<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/b><b> <\/p>\n<p><\/b><b> <\/p>\n<p><\/b><b>L\u00e9 com cr\u00e9<\/b>  <\/p>\n<p>Dizer <i>C\u00fapula Am\u00e9rica do Sul\u2014Pa\u00edses \u00c1rabes? <\/i>N\u00e3o<i>.<\/i> O nome mistura continente com pa\u00edses. Cai na mesma  esparrela quem diz &#8220;Acordo Europa \u2014 Estados Unidos&#8221;. Melhor: <i>Acordo Estados  Unidos \u2014 Pa\u00edses Europeus <\/i>(pa\u00eds com pa\u00eds).  <\/p>\n<p>Como respeitar o paralelismo? H\u00e1 v\u00e1rias sa\u00eddas:  <\/p>\n<p>1. Continente com continente: <i>C\u00fapula Am\u00e9rica do Sul \u2014 Oriente  M\u00e9dio<\/i>  <\/p>\n<p>2. Pa\u00eds com pa\u00eds: C\u00fapula dos Pa\u00edses \u00c1rabes e Sul-Americanos  <\/p>\n<p>3. Nacionalidade com nacionalidade: <i>C\u00fapula dos \u00c1rabes e dos  Sul-Americanos.<\/i><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/b><b> <\/p>\n<p><\/b><b> <\/p>\n<p><\/b> <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O corpo ensina a li\u00e7\u00e3o \u00e0 l\u00edngua. Fun\u00e7\u00f5es iguais t\u00eam estruturas iguais. Temos dois ouvidos. Eles desempenham o mesmo papel. Ouvem. Temos dois olhos. Um e outro veem. Temos duas narinas. Ambas cheiram. Temos dois bra\u00e7os. A duplinha abra\u00e7a. As duas pernas? Andam. Os 10 dedos? Seguram. Boa aluna, a l\u00edngua vai atr\u00e1s. Se a ora\u00e7\u00e3o tem termos compostos, todos ter\u00e3o a mesma cara. Se [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5054","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5054"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5054\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}