{"id":5033,"date":"2010-03-05T12:00:00","date_gmt":"2010-03-05T15:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-544\/"},"modified":"2015-11-12T16:51:00","modified_gmt":"2015-11-12T18:51:00","slug":"erramos-544","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-544\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;Ar-condicionado e ventiladores matam o  mosquito. Mentira. Estes aparelhos apenas apontam o mosquito&#8221;, escrevemos na  p\u00e1g. 32. Trope\u00e7amos no demonstrativo. No caso, o pronome indica refer\u00eancia  anterior. \u00c9 a vez do esse: <i>Ar-condicionado e ventiladores matam o mosquito.  Mentira. <b>Esses<\/b> aparelhos apenas apontam o mosquito.<\/i>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Ar-condicionado e ventiladores matam o mosquito. Mentira. Estes aparelhos apenas apontam o mosquito&#8221;, escrevemos na p\u00e1g. 32. Trope\u00e7amos no demonstrativo. No caso, o pronome indica refer\u00eancia anterior. \u00c9 a vez do esse: Ar-condicionado e ventiladores matam o mosquito. Mentira. Esses aparelhos apenas apontam o mosquito.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-5033","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5033"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5033\/revisions"}],"predecessor-version":[{"id":10651,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5033\/revisions\/10651"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}