{"id":5020,"date":"2010-12-08T00:00:00","date_gmt":"2010-12-08T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_sete_pecados_das_locucoes\/"},"modified":"2015-11-12T19:32:16","modified_gmt":"2015-11-12T21:32:16","slug":"os_sete_pecados_das_locucoes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_sete_pecados_das_locucoes\/","title":{"rendered":"Os sete pecados das locu\u00e7\u00f5es"},"content":{"rendered":"<p>&nbsp;  <\/p>\n<p> O gato tem sete vidas? Ningu\u00e9m contou. Mas todos dizem que sim. A cren\u00e7a se baseia nas caracter\u00edsticas do bichano. Ele \u00e9 \u00e1gil, resistente e exibe senhor equil\u00edbrio. Quando cai, cai de p\u00e9, sobre as quatro patas. Machuca-se? Nem pensar. Sai ileso do tombo. Mais: esperto, o peludo escapa dos predadores. O corpo flex\u00edvel, a vis\u00e3o penetrante e a audi\u00e7\u00e3o agu\u00e7ada lhe tornam a fuga pra l\u00e1 de f\u00e1cil.   <\/p>\n<p> &nbsp; Sete s\u00e3o as caracter\u00edsticas que asseguram a longevidade do felino \u2014 agilidade, resist\u00eancia, equil\u00edbrio, esperteza, flexibilidade, audi\u00e7\u00e3o e vis\u00e3o. Sete s\u00e3o as express\u00f5es que nos condenam ao fogo eterno. Basta um descuido e l\u00e1 vem a ca\u00edda impiedosa. Nos subterr\u00e2neos, o capeta espera com o tridente em brasa. Valha-nos, Deus! N\u00e3o nos deixeis cair na tenta\u00e7\u00e3o de confundir sete alhos com sete bugalhos.&nbsp;  <\/p>\n<p>&nbsp;  <\/p>\n<p> <strong> <\/p>\n<p><\/strong><strong>Oito ou oitenta<\/strong>  <\/p>\n<p> &nbsp; \u00c0 medida que ou na medida em que? Depende. Ambas se parecem como irm\u00e3s g\u00eameas. Mas, como diz o outro, parecido n\u00e3o \u00e9 igual. Mas confunde. N\u00e3o caia na desaten\u00e7\u00e3o. Abra os olhos e aguce os sentidos:   <\/p>\n<p>\u00c0 medida que = \u00e0 propor\u00e7\u00e3o que: Minha reda\u00e7\u00e3o melhora \u00e0 medida que escrevo.   <\/p>\n<p>Na medida em que = porque, tendo em vista: A dengue se alastra na medida em que n\u00e3o se combatem os focos do mosquito transmissor.   <\/p>\n<p>Pecado: cometer cruzamentos. Parte de uma estrutura se junta a parte de outra. Nascem os mostrengos \u00e0 medida em que ou na medida que. X\u00f4, satan\u00e1s! Acuda-nos, Senhor! Pra n\u00e3o cair em tenta\u00e7\u00e3o, lembre-se do 8 ou 80. \u00c0 medida que tem tr\u00eas palavras. Na medida em que, cinco. Com elas, a coluna do meio n\u00e3o tem vez.  <\/p>\n<p>&nbsp;  <\/p>\n<p> <strong> <\/p>\n<p><\/strong><strong>A favor ou contra<\/strong>  <\/p>\n<p> &nbsp; Ao encontro ou de encontro? Ops! Uma express\u00e3o \u00e9 o contr\u00e1rio da outra. Trocar as bolas \u00e9 o passaporte para as fogueirinhas do tinhoso:  <\/p>\n<p>De encontro = contra, no sentido contr\u00e1rio, em oposi\u00e7\u00e3o: O carro foi de encontro ao poste.   <\/p>\n<p>Ao encontro de = em favor de, na dire\u00e7\u00e3o de: O neto caminhou ao encontro dos av\u00f3s. Vou ao encontro do meu sonho.  <\/p>\n<p>&nbsp;  <\/p>\n<p>No come\u00e7o, em tese  <\/p>\n<p>A princ\u00edpio ou em princ\u00edpio? Ops!   <\/p>\n<p>A princ\u00edpio = inicialmente, no come\u00e7o: A princ\u00edpio, ningu\u00e9m acreditava na vit\u00f3ria de Dilma Rousseff. Depois, com o resultado das pesquisas, as opini\u00f5es mudaram.   <\/p>\n<p>Em princ\u00edpio = antes de mais nada, teoricamente, em tese: Em princ\u00edpio, toda mudan\u00e7a \u00e9 ben\u00e9fica.  <\/p>\n<p>&nbsp;  <\/p>\n<p>Contr\u00e1rios e substitui\u00e7\u00f5es  <\/p>\n<p>Ao inv\u00e9s de ou em vez de? Conhe\u00e7a a diferen\u00e7a entre uma e a outra. Depois, navegue na superdica:   <\/p>\n<p>Ao inv\u00e9s de = ao contr\u00e1rio de: Morreu ao inv\u00e9s de viver. Comeu ao inv\u00e9s de jejuar. Dormiu ao inv\u00e9s de ficar acordado.   <\/p>\n<p>Em vez de = em lugar de: Comeu peixe em vez de carne. Foi ao teatro em vez de ir ao cinema. Escreveu em vez de ler.  <\/p>\n<p>Superdica: deixe ao inv\u00e9s de pra l\u00e1. Em vez de vale pelas duas: Morreu em vez de viver. Dormiu em vez de ficar acordado.  <\/p>\n<p>&nbsp;  <\/p>\n<p>Saber \u00e0 altura  <\/p>\n<p>A par ou ao par? Olho vivo:  <\/p>\n<p>A par = estar por dentro, inteirado, sabedor das coisas: Estou a par dos bastidores da forma\u00e7\u00e3o do minist\u00e9rio Dilma.  <\/p>\n<p>Ao par = estar emparelhado: A pesquisa brasileira n\u00e3o est\u00e1 ao par da americana.  <\/p>\n<p>&nbsp;  <\/p>\n<p>\u00c0s vezes ou sempre  <\/p>\n<p>Aos domingos ou nos domingos? Se a a\u00e7\u00e3o se repete, \u00e9 a vez da preposi\u00e7\u00e3o a. Se ocorre uma vez ou de vez em quando, em: Vou \u00e0 missa aos domingos. Estudo ingl\u00eas \u00e0s segundas e quartas. Marcelo se casou no s\u00e1bado. Ele foi batizado no \u00faltimo domingo.  <\/p>\n<p>&nbsp;  <\/p>\n<p>No \u00e2mbito, \u00e0 altura  <\/p>\n<p>Em n\u00edvel de ou ao n\u00edvel de? A duplinha tem fun\u00e7\u00e3o bem definida. Ei-la:   <\/p>\n<p>Em n\u00edvel de = no \u00e2mbito de: Fa\u00e7o um curso em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. A decis\u00e3o foi tomada em n\u00edvel de diretoria.  <\/p>\n<p>Ao n\u00edvel de = \u00e0 altura de: Recife fica ao n\u00edvel do mar.   <\/p>\n<p>Pecado: a n\u00edvel de. Eta praga feia. O trio n\u00e3o existe. Fuja dele como o diabo da cruz .   <\/p>\n<p>Superdica: em n\u00edvel de existe. Mas \u00e9 dispens\u00e1vel. Sobra. Sem ele, a frase ganha em concis\u00e3o e eleg\u00e2ncia: Fa\u00e7o um curso de p\u00f3s-gradua\u00e7\u00e3o. A decis\u00e3o foi tomada pela diretoria.  <\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O gato tem sete vidas? Ningu\u00e9m contou. Mas todos dizem que sim. A cren\u00e7a se baseia nas caracter\u00edsticas do bichano. Ele \u00e9 \u00e1gil, resistente e exibe senhor equil\u00edbrio. Quando cai, cai de p\u00e9, sobre as quatro patas. Machuca-se? Nem pensar. Sai ileso do tombo. Mais: esperto, o peludo escapa dos predadores. O corpo flex\u00edvel, a vis\u00e3o penetrante e a audi\u00e7\u00e3o agu\u00e7ada lhe tornam a [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,61],"tags":[],"class_list":["post-5020","post","type-post","status-publish","format-standard","hentry","category-geral","category-pecados-da-lingua"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5020"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5020\/revisions"}],"predecessor-version":[{"id":11150,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5020\/revisions\/11150"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}