{"id":5004,"date":"2010-03-02T12:00:00","date_gmt":"2010-03-02T15:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/jairo_luis_brod_escreve\/"},"modified":"2010-03-02T12:00:00","modified_gmt":"2010-03-02T15:00:00","slug":"jairo_luis_brod_escreve","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/jairo_luis_brod_escreve\/","title":{"rendered":"Jairo Luis Brod escreve"},"content":{"rendered":"\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&nbsp; Querida Dad,<\/p><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;  <\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Com a  partida de um dos maiores brasileiros de todos os tempos (o Mindlin), revi na  imprensa duas sonoras palavrinhas que h\u00e1 tempos andavam  esquecidas:<\/p><\/div>\n<p>&nbsp;<strong> incun\u00e1bulos  <\/strong>(os primeiros livros impressos, que v\u00e3o de meados dos 1400 ao final dos  1600); <\/p>\n<p>&nbsp; <strong>ex-l\u00edbris,  <\/strong>revivido em seu blog: &#8220;N\u00e3o fa\u00e7o nada sem alegria&#8221;,&nbsp;anuncia o <strong>ex-libris<\/strong> das obras  que&nbsp;o bibli\u00f3filo  acariciou&#8221;. <\/p>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;  <\/p>\n<p>Chique  voc\u00ea,&nbsp;o d\u00edstico dos livros mindlinianos e o autor dessa verdadeira profiss\u00e3o de  f\u00e9,&nbsp;que o viveu \u00e0 perfei\u00e7\u00e3o.<\/p><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\" align=\"left\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Querida Dad, &nbsp; &nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Com a partida de um dos maiores brasileiros de todos os tempos (o Mindlin), revi na imprensa duas sonoras palavrinhas que h\u00e1 tempos andavam esquecidas: &nbsp; incun\u00e1bulos (os primeiros livros impressos, que v\u00e3o de meados dos 1400 ao final dos 1600); &nbsp; ex-l\u00edbris, revivido em seu blog: &#8220;N\u00e3o fa\u00e7o nada sem alegria&#8221;,&nbsp;anuncia o ex-libris das obras que&nbsp;o bibli\u00f3filo acariciou&#8221;. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5004","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=5004"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/5004\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=5004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=5004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=5004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}