{"id":4942,"date":"2010-11-30T08:00:00","date_gmt":"2010-11-30T10:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-78\/"},"modified":"2015-11-13T10:23:28","modified_gmt":"2015-11-13T12:23:28","slug":"leitor_pergunta-78","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-78\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"\n<p><b> <\/p>\n<p><\/b><i> <\/i><i style=\"font-weight: bold\">Cateter<\/i><b style=\"font-weight: bold\"> <\/b>e<b style=\"font-weight: bold\">  <\/b><i style=\"font-weight: bold\">ureter<\/i><b style=\"font-weight: bold\"> <\/b>se escrevem sem acento. A s\u00edlaba t\u00f4nica deveria ser a  \u00faltima. Mas ou\u00e7o at\u00e9 m\u00e9dicos dizerem &#8220;cat\u00e9ter&#8221; e &#8220;ur\u00e9ter&#8221;. E da\u00ed? (Telmo Cavalcanti) <\/p>\n<p><b>  <\/p>\n<p><\/b> Voc\u00ea tem raz\u00e3o, Telmo. A pron\u00fancia nota 10 p\u00f5e as duas  mocinhas na turma das ox\u00edtonas. \u00c9 como bater, comover e remover. Mas &#8220;ur\u00e9ter&#8221; e  &#8220;cat\u00e9ter&#8221; est\u00e3o t\u00e3o generalizados que os dicion\u00e1rios os citam como modismo  brasileiro. Em resumo: aceitam-se as duas&nbsp;formas. .  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cateter e ureter se escrevem sem acento. A s\u00edlaba t\u00f4nica deveria ser a \u00faltima. Mas ou\u00e7o at\u00e9 m\u00e9dicos dizerem &#8220;cat\u00e9ter&#8221; e &#8220;ur\u00e9ter&#8221;. E da\u00ed? (Telmo Cavalcanti) Voc\u00ea tem raz\u00e3o, Telmo. A pron\u00fancia nota 10 p\u00f5e as duas mocinhas na turma das ox\u00edtonas. \u00c9 como bater, comover e remover. Mas &#8220;ur\u00e9ter&#8221; e &#8220;cat\u00e9ter&#8221; est\u00e3o t\u00e3o generalizados que os dicion\u00e1rios os citam como modismo brasileiro. Em resumo: [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-4942","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4942"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4942\/revisions"}],"predecessor-version":[{"id":11404,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4942\/revisions\/11404"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}