{"id":4890,"date":"2010-11-22T00:00:00","date_gmt":"2010-11-22T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_cravo_nao_brigou_com_a_rosa\/"},"modified":"2010-11-22T00:00:00","modified_gmt":"2010-11-22T02:00:00","slug":"o_cravo_nao_brigou_com_a_rosa","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_cravo_nao_brigou_com_a_rosa\/","title":{"rendered":"O cravo n\u00e3o brigou com a rosa"},"content":{"rendered":"<div>\n<div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div> por Luiz Antonio Simas   <\/p>\n<p>Chegamos ao limite da insanidade da onda do politicamente correto.&nbsp; Soube dia desses que as crian\u00e7as, nas creches e escolas, n\u00e3o cantam mais &#8220;o cravo brigou com a rosa&#8221;. A explica\u00e7\u00e3o da professora do filho de um camarada foi comovente: &#8220;A briga entre o cravo (o homem) e a rosa (a mulher) estimula a viol\u00eancia entre os casais. Na nova letra &#8220;o cravo encontrou a rosa\/ debaixo de uma sacada\/o cravo ficou feliz \/e a rosa ficou encantada&#8221;. &nbsp; Que diabos \u00e9 isso? O pr\u00f3ximo passo \u00e9 enquadrar o cravo na Lei Maria da Penha.&nbsp; Ser\u00e1 que esses doidos sabem que O cravo brigou com a rosa faz parte de uma su\u00edte de 16 pe\u00e7as que Villa Lobos criou a partir de temas recolhidos no folclore brasileiro? \u00c9 Villa Lobos, cacete! &nbsp; Outra m\u00fasica infantil que mudou de letra foi Samba Lel\u00ea. Na vers\u00e3o da minha inf\u00e2ncia, o neg\u00f3cio era o seguinte: &#8220;Samba Lel\u00ea t\u00e1 doente\/ T\u00e1 com a cabe\u00e7a quebrada\/ Samba Lel\u00ea precisava\/ \u00c9 de umas boas palmadas&#8221;. A palmada na bunda est\u00e1 proibida. Incita a viol\u00eancia contra a menina Lel\u00ea. A tia do maternal agora ensina assim: &#8220;Samba Lel\u00ea t\u00e1 doente\/ Com uma febre malvada\/&nbsp; Assim que a febre passar\/ A Lel\u00ea vai estudar.   <\/p>\n<p>Se eu fosse a Lel\u00ea, com uma vers\u00e3o dessas, torcia pra febre n\u00e3o passar nunca. Os amigos sabem de quem \u00e9&nbsp;Samba Lel\u00ea? Villa Lobos de novo. Podiam at\u00e9 registrar a parceria. Ficaria assim: &#8220;Samba Lel\u00ea, de Heitor Villa Lobos e Tia Nilda do Jardim Escola Crian\u00e7a Feliz&#8221;.   <\/p>\n<p>Comunico tamb\u00e9m que n\u00e3o se pode mais atirar o pau no gato, j\u00e1 que a m\u00fasica desperta nas crian\u00e7as o desejo de maltratar os bichinhos. Quem entra na roda dan\u00e7a, nos dias atuais, n\u00e3o pode mais ter sete namorados para se casar com um. Sete namorados \u00e9 coisa de menina f\u00e1cil. Ningu\u00e9m&nbsp; mais \u00e9 pobre ou rico de marr\u00e9-de-si, para n\u00e3o despertar na garotada o sentido da desigualdade social entre os homens.   <\/p>\n<p>Dia desses algu\u00e9m [n\u00e3o me lembro exatamente quem se saiu com essa e n\u00e3o procurei a refer\u00eancia no meu babalorix\u00e1 virtual,&nbsp; Pai Google da Aruanda] foi espinafrado porque disse que ecologia era, nos anos setenta, coisa de veado. Qual \u00e9 o problema da frase? Ecologia, de fato,&nbsp; era vista como coisa de viado. Eu imagino se meu av\u00f4, com a alma de cangaceiro que possu\u00eda, soubesse, em mil novecentos e setenta e poucos, que algum filho estava militando na causa da preserva\u00e7\u00e3o do mico-le\u00e3o-dourado, em defesa das brom\u00e9lias ou coisa que o valha.&nbsp;   <\/p>\n<p>Vivemos tempos de n\u00e3o me toques que eu magoo. Quer dizer que ningu\u00e9m mais pode usar a express\u00e3o coisa de veado? Que me desculpem os paladinos da cartilha da corre\u00e7\u00e3o, mas isso \u00e9 uma tremenda babaquice. O politicamente correto \u00e9 a sepultura do bom humor, da criatividade, da boa sacanagem. A express\u00e3o coisa de veado n\u00e3o \u00e9, nem a pau (sem duplo sentido), ofensa a bicha alguma.   <\/p>\n<p>Daqui a pouco s\u00f3 chamaremos o an\u00e3o&nbsp;&#8212; o popular pintor de rodap\u00e9 ou le\u00e3o de ch\u00e1cara de baile infantil &#8212; de deficiente vertical. O crioulo &#8212; vulgo picol\u00e9 de asfalto ou bola sete (depende do peso) &#8212; s\u00f3 pode ser chamado de afrodescendente. O branquelo &#8212; o famoso branco azedo ou Omo total &#8212; \u00e9 um cidad\u00e3o caucasiano desprovido de pigmenta\u00e7\u00e3o mais evidente. A mulher feia &#8212; aquela que nasceu pelo avesso, a soldado do quinto batalh\u00e3o de artilharia pesada, tamb\u00e9m conhecida como o rascunho do mapa do inferno &#8212; \u00e9 apenas a dona de um padr\u00e3o divergente dos preceitos est\u00e9ticos da contemporaneidade. O gordo &#8212; outrora conhecido como rolha de po\u00e7o, chupeta do Ves\u00favio, Orca, baleia assassina e buj\u00e3o &#8212; \u00e9 o cidad\u00e3o que est\u00e1 fora do peso ideal. O magricela n\u00e3o pode ser chamado de morto de fome, pau de virar tripa e Ol\u00edvia Palito. O careca n\u00e3o \u00e9 mais o aeroporto de mosquito, tobog\u00e3 de piolho e pouca telha.   <\/p>\n<p>Nas aulas sobre o barroco mineiro, n\u00e3o poderei mais citar o Aleijadinho. Direi o seguinte: o escultor Ant\u00f4nio Francisco Lisboa tinha necessidades especiais&#8230; N\u00e3o d\u00e1. O politicamente correto tamb\u00e9m gera a morte do apelido, essa tradi\u00e7\u00e3o fabulosa do Brasil.   <\/p>\n<p>O recente Estatuto do Torcedor quer, com os olhos gordos na Copa e 2014, disciplinar as manifesta\u00e7\u00f5es das torcidas de futebol. Em vez de xingar a m\u00e3e do juiz, e o centroavante pereba tomar naquele lugar, cantaremos nas arquibancadas o allegro da Nona Sinfonia de Beethoven, entremeado pelo coro de Jesus, alegria dos homens, do velho Bach.   <\/p>\n<p>Falei em velho Bach e me lembrei de outra. A velhice n\u00e3o existe mais. O sujeito cheio de pelancas, doente, acabado, o famoso p\u00e9 na cova,&nbsp; aquele que dobrou o Cabo da Boa Esperan\u00e7a, o cliente do seguro funeral, o popular t\u00e1 mais pra l\u00e1 do que pra c\u00e1,&nbsp; j\u00e1 tem motivos para sorrir na beira da sepultura. A velhice agora \u00e9 simplesmente a &#8220;melhor idade&#8221;.   <\/p>\n<p>Se Deus quiser, morreremos, todos, gozando da mais perfeita sa\u00fade. Defuntos? N\u00e3o. Seremos os inquilinos do condom\u00ednio Cidade do P\u00e9 Junto.<\/p><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;   <\/p>\n<div align=\"justify\">(Colabora\u00e7\u00e3o da Lilian)   <\/p>\n<p>&nbsp;<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; por Luiz Antonio Simas Chegamos ao limite da insanidade da onda do politicamente correto.&nbsp; Soube dia desses que as crian\u00e7as, nas creches e escolas, n\u00e3o cantam mais &#8220;o cravo brigou com a rosa&#8221;. A explica\u00e7\u00e3o da professora do filho de um camarada foi comovente: &#8220;A briga entre o cravo (o homem) e a rosa (a mulher) estimula a viol\u00eancia entre os casais. Na [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4890","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4890"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4890\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}